{"id":1826498,"date":"2026-07-14T22:41:30","date_gmt":"2026-07-14T22:41:30","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1826498"},"modified":"2026-07-14T22:41:30","modified_gmt":"2026-07-14T22:41:30","slug":"a-estrela-de-tv-canadense-katherine-ryan-nomeia-seu-filho-favorito-e-chama-seus-outros-tres-filhos-de-nepo-babies","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/a-estrela-de-tv-canadense-katherine-ryan-nomeia-seu-filho-favorito-e-chama-seus-outros-tres-filhos-de-nepo-babies\/","title":{"rendered":"A estrela de TV canadense Katherine Ryan nomeia seu filho \u2018favorito\u2019 e chama seus outros tr\u00eas filhos de \u2018Nepo-Babies\u2019"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<figure><\/figure>\n<\/p>\n<div data-article-body=\"true\" data-body-type=\"bodyblocks\">\n<h3 class=\"mb-4 text-lg font-bold\">PRECISO SABER<\/h3>\n<ul class=\"mb-4\">\n<li class=\"ml-4 safari:ml-6 list-disc\">\n<div>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Katherine Ryan revelou em um podcast que sua filha mais velha, Violet, a quem ela acolheu em um relacionamento anterior, \u00e9 sua filha favorita<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<ul class=\"mb-4\">\n<li class=\"ml-4 safari:ml-6 list-disc\">\n<div>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Ryan divide tr\u00eas filhos mais novos com o marido e diz que a educa\u00e7\u00e3o de Violet foi diferente da de seus irm\u00e3os<\/p>\n<\/div>\n<\/li>\n<li class=\"ml-4 safari:ml-6 list-disc\">\n<div>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Os f\u00e3s ficaram divididos com seus coment\u00e1rios, com alguns expressando desaprova\u00e7\u00e3o e outros defendendo sua honestidade<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<p class=\"mb-4 text-lg md:leading-8 break-words\"><a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:Katherine Ryan;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"https:\/\/www.instagram.com\/kathbum\/?hl=en\">Katherine Ryan<\/a> n\u00e3o est\u00e1 brincando quando se trata de qual de seus filhos \u00e9 seu favorito.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Ao aparecer no <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:Begin Again with Davina McCall;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"https:\/\/podcasts.apple.com\/us\/podcast\/begin-again-with-davina-mccall\/id1773104705\">Comece de novo com Davina McCall<\/a> podcast em outubro passado, a comediante canadense, 43, compartilhou que ela tem um favorito de seus quatro filhos &#8211; e defendeu sua decis\u00e3o de revelar qual \u00e9.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">&#8220;Posso dizer. Violet \u00e9 minha favorita. Ela \u00e9 a filha primog\u00eanita&#8221;, disse Ryan. &#8220;E acho que as pessoas n\u00e3o gostam disso. Isso tamb\u00e9m \u00e9 algo muito provocativo de se dizer.&#8221;<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Ryan divide seus tr\u00eas filhos mais novos \u2013 Fred, Fanna e Holland \u2013 com seu marido Bobby Kootstra. Ela \u00e9 m\u00e3e da filha Violet, de 17 anos, de um relacionamento anterior.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cE n\u00e3o me preocupo com a possibilidade de isso ferir os sentimentos dos meus outros filhos, porque digo: &#8216;Esses s\u00e3o beb\u00eas nepo&#8217;. Tipo, adivinhe? Ela \u00e9 minha favorita\u201d, continuou Ryan. \u201cVoc\u00ea vai para uma escola particular. Ela \u00e9 minha favorita. Voc\u00ea cresce com um pai. A vida n\u00e3o \u00e9 justa. Ela \u00e9 minha favorita.\u201d<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Nunca perca uma hist\u00f3ria &#8211; inscreva-se para <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:PEOPLE&apos;s free daily newsletter;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"https:\/\/people.com\/people-news-daily-newsletter-sign-up-8692701\">Boletim informativo di\u00e1rio gratuito da PEOPLE<\/a> para se manter atualizado sobre o que a PEOPLE tem de melhor a oferecer, desde not\u00edcias de celebridades at\u00e9 hist\u00f3rias atraentes de interesse humano.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Um clipe do podcast foi compartilhado novamente em <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:a Facebook page;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"https:\/\/www.facebook.com\/61567727813810\/videos\/katherine-ryan-reveals-her-favourite-child-\/1707336896978277\/\">uma p\u00e1gina do Facebook<\/a> para o podcast de McCall, e muitos seguidores compartilharam sua desaprova\u00e7\u00e3o pelos coment\u00e1rios de Ryan.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cN\u00e3o, absolutamente n\u00e3o, voc\u00ea n\u00e3o pode [sic] escolha um filho favorito&#8221;, escreveu uma pessoa. &#8220;Voc\u00ea os ama igualmente para seus pr\u00f3prios prop\u00f3sitos individuais.&#8221;<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cMesmo sendo m\u00e3e, se eu tivesse esses sentimentos, n\u00e3o acho que contaria a eles!\u201d disse outro.<\/p>\n<div class=\"relative\"><img decoding=\"async\" alt=\"Katherine RyanCr\u00e9dito: Comece de novo com Davina McCall\/YouTube\" loading=\"lazy\" width=\"960\" height=\"640\" data-nimg=\"1\" class=\"rounded-lg\" src=\"https:\/\/s.yimg.com\/lo\/mysterio\/api\/4125ccfcffb01f286040510e2dc52dd1647b2ed5caf8e63c921bdefc4a9d0310\/lightyear_networkapi\/resizefill_w960;quality_80;format_webp\/https:%2F%2Fmedia.zenfs.com%2Fen%2Fpeople_218%2Fc077dec26d561cef1b0b72c11f4d9188\" \/><span class=\"absolute bottom-3 right-3 rounded-full bg-primary p-3 opacity-100 shadow-elevation-3 transition-opacity duration-300 group-hover:block group-hover:opacity-100 md:p-[17px] lg:bottom-6 lg:right-6 lg:bg-primary\/90 lg:p-5 lg:opacity-0 lg:shadow-none\"><\/span><\/div>\n<p><i>Katherine Ryan<br \/>Cr\u00e9dito: Comece de novo com Davina McCall\/YouTube<\/i><\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">No entanto, alguns outros entraram na conversa e defenderam Ryan, dizendo que entendiam o que a m\u00e3e de quatro filhos estava tentando transmitir.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cEla \u00e9 mais protetora com a mais velha porque n\u00e3o tem pai em sua vida e eles viajaram juntos, enquanto as crian\u00e7as mais novas pegaram a vers\u00e3o melhor dela que j\u00e1 havia alcan\u00e7ado o sucesso\u201d, escreveu um terceiro comentarista. \u201cAcho que \u00e9 isso que ela est\u00e1 tentando dizer.\u201d<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cAcho que muitos pais t\u00eam um filho favorito, mas \u00e9 um tabu admitir isso\u201d, disse outro. \u201cAssim como a maioria das pessoas tem um pai, irm\u00e3o, animal de estima\u00e7\u00e3o, amigo, primo, etc. favorito\u2026\u201d<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Leia o artigo original em <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:People;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"https:\/\/people.com\/katherine-ryan-names-her-favorite-child-calls-others-privileged-nepo-babies-12019363\">Pessoas<\/a><\/p>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.yahoo.com&#8217; <\/em><\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<em> \u2018O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros\u2019<br \/>\n<\/em><\/p>\n<p><em> \u2018 Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte celebrity.land \u2019 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRECISO SABER Katherine Ryan revelou em um podcast que sua filha mais velha, Violet, a quem ela acolheu em um relacionamento anterior, \u00e9 sua filha favorita Ryan divide tr\u00eas filhos mais novos com o marido e diz que a educa\u00e7\u00e3o de Violet foi diferente da de seus irm\u00e3os Os f\u00e3s ficaram divididos com seus coment\u00e1rios, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1826499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1826498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estrelas"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1826498"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826498\/revisions"}],"predecessor-version":[{"id":1826500,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826498\/revisions\/1826500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1826499"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1826498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1826498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1826498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}