{"id":1826699,"date":"2026-07-15T02:33:48","date_gmt":"2026-07-15T02:33:48","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1826699"},"modified":"2026-07-15T02:33:48","modified_gmt":"2026-07-15T02:33:48","slug":"brat-anuncia-album-manslayer-e-estreia-novo-single","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/brat-anuncia-album-manslayer-e-estreia-novo-single\/","title":{"rendered":"BRAT anuncia \u00e1lbum \u2018Manslayer\u2019 e estreia novo single"},"content":{"rendered":"\n<figure><\/figure>\n<\/p>\n<div>\n<div class=\"juiz_sps_links  counters_both juiz_sps_displayed_both\" data-post-id=\"67009\">\n<p class=\"screen-reader-text juiz_sps_maybe_hidden_text\">Compartilhe a postagem \u201cBRAT revela novo \u00e1lbum &#8216;Manslayer&#8217;, lan\u00e7a v\u00eddeo de \u201cManslayer (Hell Hath No Fury)\u201d\u201d<\/p>\n<\/p>\n<\/div>\n<p>A banda de death metal da Louisiana, BRAT, anunciou seu segundo \u00e1lbum, <em>Homicida<\/em>com lan\u00e7amento previsto para 25 de setembro pela Prosthetic Records.<\/p>\n<p>Junto com o an\u00fancio, a banda lan\u00e7ou o primeiro single do \u00e1lbum, \u201cManslayer (Hell Hath No Fury)\u201d, acompanhado por um novo videoclipe dirigido por John Colgan.<\/p>\n<p>Produzido, projetado e mixado por Andy Nelson do Weekend Nachos na Bricktop Recording em Chicago e masterizado por Brad Boatright (Deadguy, Pig Destroyer), <em>Homicida<\/em> segue a estreia do BRAT em 2024, <em>Gra\u00e7a Social<\/em>. O esfor\u00e7o de 17 faixas mistura death metal, thrash e hardcore enquanto expande o som caracter\u00edstico da banda com temas mais sombrios.<\/p>\n<p>Liricamente, a vocalista Liz Selfish se inspirou em uma fonte inesperada: a m\u00fasica country.<\/p>\n<p>\u201cN\u00e3o existem muitos desses tropos no death metal\u201d, disse Selfish. \u201cAchei que era uma perspectiva muito legal e gostei muito do aspecto narrativo dela.\u201d<\/p>\n<p>M\u00fasicas como \u201cGoodbye Earl\u201d dos The Chicks, \u201cBefore He Cheats\u201d de Carrie Underwood e \u201cGunpowder &#038; Lead\u201d de Miranda Lambert ajudaram a inspirar a narrativa movida pela vingan\u00e7a do \u00e1lbum, que inverte a narrativa tradicional do metal extremo ao colocar as mulheres no papel de vingadoras em vez de v\u00edtimas.<\/p>\n<p>Manslayer tamb\u00e9m marca a primeira vez que Selfish lidou com as letras do \u00e1lbum na \u00edntegra, assumindo as tarefas de reda\u00e7\u00e3o das letras enquanto o guitarrista Brenner Moate se concentrava em compor a m\u00fasica.<\/p>\n<p>\u201c\u00c9 um territ\u00f3rio bastante novo para mim\u201d, explicou Selfish. &#8220;Eu escrevi a primeira m\u00fasica do \u00e1lbum e simplesmente adorei escrever&#8230; Acabei escrevendo o \u00e1lbum inteiro. O foco principal do Brenner \u00e9 escrever m\u00fasicas &#8211; ele quer escrever riffs &#8211; ent\u00e3o foi uma boa passagem de tocha.&#8221;<\/p>\n<p>A capa do \u00e1lbum foi criada por Wes Benscoter, cujo trabalho anterior inclui lan\u00e7amentos de Slayer e Mortician.<\/p>\n<p><strong><em>Homicida<\/em> lista de faixas:<\/strong><br \/>1. Introdu\u00e7\u00e3o<br \/>2. Aileen Wuornos<br \/>3. Sangramento do esp\u00e9culo<br \/>4. Esporas \u00f3sseas<br \/>5. Falha cr\u00edtica Tox<br \/>6. Desperd\u00edcio de m\u00eddia<br \/>7. Ca\u00e7a ao Trof\u00e9u<br \/>8. Pedindo pelo Inferno<br \/>9. Queima Herege<br \/>10. Interl\u00fadio<br \/>11. Homicida (O Inferno N\u00e3o Tem F\u00faria)<br \/>12. Maria Sangrenta<br \/>13. Vingan\u00e7a Femicida (feat. David Davidson da Revoga\u00e7\u00e3o)<br \/>14. Cuspir em seu t\u00famulo<br \/>15. Maneiras de matar seu marido<br \/>16. L\u00ednguas Bolhas (feat. Candace Buckingham de Walls of Jericho)<br \/>17. Outro<\/p>\n<p>De acordo com a banda, <em>Homicida<\/em> representa uma evolu\u00e7\u00e3o mais sombria do som e da est\u00e9tica do BRAT, mantendo o toque ir\u00f4nico que ajudou a definir a identidade inicial do grupo.<\/p>\n<p>\u201cEstamos evoluindo a viol\u00eancia e a excentricidade, tornando tudo um pouco mais sombrio com este \u00e1lbum e um pouco mais abertamente violento\u201d, disse Selfish. \u201cAcho que isso provavelmente refletir\u00e1 em nosso show e em nossas imagens tamb\u00e9m, mantendo-o divertido\u2026 mas definitivamente progredindo para algo mais sombrio.\u201d<\/p>\n<p>Assista ao v\u00eddeo de \u201cManslayer (Hell Hath No Fury)\u201d abaixo. Pr\u00e9-encomende o disco <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/brat.ffm.to\/manslayer\">aqui<\/a>.<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><\/div>\n<div class=\"awac-wrapper\" id=\"text-30\">\n<div class=\"awac widget text-30\">\n<div class=\"textwidget\">\n<hr \/>\n<p><strong>Siga NextMosh em<\/strong>: <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/nextmosh\">Facebook<\/a>, <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/twitter.com\/nextmosh\">Twitter<\/a>, <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/nextmosh\">Instagram<\/a>, <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/user\/nextmosh\">YouTube<\/a><\/p>\n<p><em>Esta postagem pode conter links afiliados. Este site utiliza cookies e, ao continuar a utiliz\u00e1-lo, voc\u00ea concorda com o seu uso.<\/em><\/p>\n<p><a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/google.com\/preferences\/source?q=nextmosh.com\"><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"juiz_sps_links  counters_both juiz_sps_displayed_both\" data-post-id=\"67009\">\n<p class=\"screen-reader-text juiz_sps_maybe_hidden_text\">Compartilhe a postagem \u201cBRAT revela novo \u00e1lbum &#8216;Manslayer&#8217;, lan\u00e7a v\u00eddeo de \u201cManslayer (Hell Hath No Fury)\u201d\u201d<\/p>\n<\/p>\n<\/div>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte nextmosh.com&#8217; <\/em><\/p>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land   \u2019 Source Link <\/em><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Compartilhe a postagem \u201cBRAT revela novo \u00e1lbum &#8216;Manslayer&#8217;, lan\u00e7a v\u00eddeo de \u201cManslayer (Hell Hath No Fury)\u201d\u201d A banda de death metal da Louisiana, BRAT, anunciou seu segundo \u00e1lbum, Homicidacom lan\u00e7amento previsto para 25 de setembro pela Prosthetic Records. Junto com o an\u00fancio, a banda lan\u00e7ou o primeiro single do \u00e1lbum, \u201cManslayer (Hell Hath No Fury)\u201d, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1808563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1826699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1826699"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826699\/revisions"}],"predecessor-version":[{"id":1826700,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826699\/revisions\/1826700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1808563"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1826699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1826699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1826699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}