{"id":1826729,"date":"2026-07-15T03:30:43","date_gmt":"2026-07-15T03:30:43","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1826729"},"modified":"2026-07-15T03:30:43","modified_gmt":"2026-07-15T03:30:43","slug":"david-beckham-tem-uma-explicacao-hilariante-para-a-cara-viral-de-victoria-na-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/david-beckham-tem-uma-explicacao-hilariante-para-a-cara-viral-de-victoria-na-copa-do-mundo\/","title":{"rendered":"David Beckham tem uma explica\u00e7\u00e3o hilariante para a cara viral de Victoria na Copa do Mundo"},"content":{"rendered":"<figure><\/figure>\n<\/p>\n<div id=\"\">\n<div class=\"primary-cli cli cli-text \">\n<p>Victoria Beckham se tornou viral na Copa do Mundo de 2026 depois que uma foto a capturou parecendo claramente perplexa enquanto seu marido, o ex-astro do futebol ingl\u00eas David Beckham, se levantava e dava um soco no ar em comemora\u00e7\u00e3o.<\/p>\n<\/div>\n<div class=\"primary-cli cli cli-text \">\n<p>A estilista e ex-Spice Girl, conhecida como Posh Spice, permaneceu sentada enquanto seu marido comemorava a dram\u00e1tica vit\u00f3ria da Inglaterra por 2 a 1 nas quartas de final sobre a Noruega, no Miami Stadium, no s\u00e1bado.<\/p>\n<\/div>\n<figure class=\"cli cli-image js-no-inject\">\n<div class=\"img-sized\"><img decoding=\"async\" class=\"img-sized__img landscape\" loading=\"lazy\" alt=\"Victoria Beckham, \u00e0 esquerda, permanece sentada enquanto seu marido, David Beckham, \u00e0 direita, comemora a Copa do Mundo no s\u00e1bado, 11 de julho de 2026, em Miami. \" width=\"720\" height=\"395\" src=\"https:\/\/img.huffingtonpost.com\/asset\/6a562ba11a00004fc25811dc.jpeg?ops=scalefit_720_noupscale\" srcset=\"https:\/\/img.huffingtonpost.com\/asset\/6a562ba11a00004fc25811dc.jpeg?ops=scalefit_720_noupscale 1x, https:\/\/img.huffingtonpost.com\/asset\/6a562ba11a00004fc25811dc.jpeg?ops=scalefit_1440 2x\" \/><\/div>\n<p><figcaption class=\"cli-image__caption caption-cli\">Victoria Beckham, \u00e0 esquerda, permanece sentada enquanto seu marido, David Beckham, \u00e0 direita, comemora a Copa do Mundo no s\u00e1bado, 11 de julho de 2026, em Miami. <\/figcaption><\/p>\n<\/figure>\n<div class=\"primary-cli cli cli-text \">\n<p>A imagem rapidamente se espalhou online, <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/p\/DataodKAeWa\/?img_index=1\" role=\"link\" class=\" js-entry-link cet-external-link\" data-vars-item-name=\"prompting comedian Jenny Johnson to joke on Instagram\" data-vars-item-type=\"text\" data-vars-unit-name=\"6a5636f9e4b09630fcd81c27\" data-vars-unit-type=\"buzz_body\" data-vars-target-content-id=\"https:\/\/www.instagram.com\/p\/DataodKAeWa\/?img_index=1\" data-vars-target-content-type=\"url\" data-vars-type=\"web_external_link\" data-vars-subunit-name=\"article_body\" data-vars-subunit-type=\"component\" data-vars-position-in-subunit=\"0\">levando a comediante Jenny Johnson a brincar no Instagram<\/a>:<\/p>\n<\/div>\n<div class=\"primary-cli cli cli-text \">\n<blockquote>\n<p>&#8220;N\u00e3o h\u00e1 nada como torcer pela Inglaterra em casa, ent\u00e3o eles cortam para Victoria e vemos aquele sorriso cl\u00e1ssico da Posh Spice! \u00c9 t\u00e3o contagiante! Eu costumava pensar que me animava enquanto assistia esportes, mas Victoria explode meu entusiasmo! Cada vez que a vejo, eu grito: &#8216;APIMENTE SUA VIDA!!!!&#8217; porque a energia dela \u00e9 el\u00e9trica!!! Veja voc\u00ea mesmo!<\/p>\n<\/blockquote>\n<\/div>\n<div class=\"primary-cli cli cli-text \">\n<p>David Beckham juntou-se \u00e0 piada nos coment\u00e1rios, escrevendo: \u201cEla estava comemorando por dentro, eu prometo\u201d, ao lado de um emoji chorando e rindo, antes de acrescentar: \u201cAs rea\u00e7\u00f5es dela foram um pouco mais lentas que as minhas\u201d.<\/p>\n<\/div>\n<div class=\"primary-cli cli cli-text \">\n<p>Outras fotos da partida mostram Victoria Beckham muito mais animada.<\/p>\n<\/div>\n<figure class=\"cli cli-image js-no-inject\">\n<div class=\"img-sized\"><img decoding=\"async\" class=\"img-sized__img landscape\" loading=\"lazy\" alt=\"Victoria Beckham, \u00e0 esquerda, e seu marido, David Beckham, \u00e0 direita, aparecem torcendo pela Copa do Mundo no s\u00e1bado, 11 de julho de 2026, em Miami. \" width=\"720\" height=\"480\" src=\"https:\/\/img.huffingtonpost.com\/asset\/6a562bd91a000063c25811dd.jpeg?ops=scalefit_720_noupscale\" srcset=\"https:\/\/img.huffingtonpost.com\/asset\/6a562bd91a000063c25811dd.jpeg?ops=scalefit_720_noupscale 1x, https:\/\/img.huffingtonpost.com\/asset\/6a562bd91a000063c25811dd.jpeg?ops=scalefit_1440 2x\" \/><\/div>\n<p><figcaption class=\"cli-image__caption caption-cli\">Victoria Beckham, \u00e0 esquerda, e seu marido, David Beckham, \u00e0 direita, aparecem torcendo pela Copa do Mundo no s\u00e1bado, 11 de julho de 2026, em Miami. <\/figcaption><\/p>\n<\/figure>\n<aside class=\"cli cli-related-articles js-cet-subunit\" \/><\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.celebrity.land&#8217; <\/em><\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land \u2019 <\/em>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Victoria Beckham se tornou viral na Copa do Mundo de 2026 depois que uma foto a capturou parecendo claramente perplexa enquanto seu marido, o ex-astro do futebol ingl\u00eas David Beckham, se levantava e dava um soco no ar em comemora\u00e7\u00e3o. A estilista e ex-Spice Girl, conhecida como Posh Spice, permaneceu sentada enquanto seu marido comemorava [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1826730,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-1826729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fofocas"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1826729"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826729\/revisions"}],"predecessor-version":[{"id":1826731,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826729\/revisions\/1826731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1826730"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1826729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1826729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1826729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}