{"id":1826941,"date":"2026-07-15T08:43:55","date_gmt":"2026-07-15T08:43:55","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1826941"},"modified":"2026-07-15T08:43:55","modified_gmt":"2026-07-15T08:43:55","slug":"a-notavel-vida-de-dan-quisenberry","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/a-notavel-vida-de-dan-quisenberry\/","title":{"rendered":"A not\u00e1vel vida de Dan Quisenberry"},"content":{"rendered":"<figure><\/figure>\n<\/p>\n<div id=\"zephr-anchor\">\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Quando voc\u00ea ouve o nome Dan Quisenberry, qual a primeira coisa que vem \u00e0 sua mente?<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">\u00c9 o seu fabuloso recorde de arremessos? \u00c9 a sua entrega submarina incomum? Poderia ser seu senso de humor perverso? Talvez seja o cabelo ruivo e o bigode de policial \/ estrela porn\u00f4 dos anos 70?<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Pode ser tudo ou uma combina\u00e7\u00e3o dessas coisas.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Uma coisa \u00e9 certa: Dan Quisenberry foi um excelente arremessador e um ser humano \u00fanico. Nunca houve outro como ele no Royals ou na Major League Baseball, ali\u00e1s.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">O caminho de Quisenberry para as ligas principais foi t\u00e3o incomum quanto o pr\u00f3prio homem. Quiz e seu irm\u00e3o mais velho Marty, tamb\u00e9m arremessador, jogaram no pequeno Orange Coast College antes de Dan se matricular no La Verne College, onde se tornou um NAIA All-American.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Ele estava pronto para seguir em frente com sua vida p\u00f3s-beisebol quando Ben Hines, o treinador do La Verne, conversou com o lend\u00e1rio olheiro do Royals, Rosey Gilhousen, o homem que observou George Brett.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Gilhousen mencionou que eles precisavam de um arremessador adicional na Classe A Waterloo, e Hines respondeu: \u201cTenho um cara para voc\u00ea\u201d.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Dan dirigiu seu Gremlin surrado (lembra deles?) Por dez minutos at\u00e9 a casa de Rosey em Santa Ana e assinou por US$ 500 por m\u00eas, mais um bast\u00e3o, caneta e bot\u00e3o de lapela do Royals.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Dan foi para Waterloo, o que deve ter sido um choque cultural vindo de Los Angeles. No domingo, 22 de junho de 1975, Dan compareceu aos cultos na Igreja de Cristo, uma grande igreja de tijolos localizada na rua 4, e foi batizado. Naquela tarde, ele fez sua estreia profissional, conquistando uma vit\u00f3ria completa de sete entradas sobre o Wausau no primeiro jogo de uma partida dupla. Este foi o primeiro e \u00faltimo in\u00edcio de Quiz como arremessador profissional. O t\u00e9cnico John Sullivan informou-o ap\u00f3s o jogo que ele estava sendo transferido para o bullpen porque precisava de um arremessador substituto que pudesse lan\u00e7ar rebatidas.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Aquela equipe de Waterloo de 1975 era outra coisa. Os moradores mais antigos ainda falam sobre eles. Eles terminaram com um recorde de 93-35. Sua porcentagem de vit\u00f3rias de 0,726 ainda est\u00e1 entre as melhores da hist\u00f3ria das ligas menores. Apesar disso, o time n\u00e3o estava carregado de futuras estrelas. Quisenberry e o outfielder Willie Wilson, de 19 anos, foram os \u00fanicos que tiveram um grande impacto. German Barranca, Charlie Beamon, Roy Branch, Joe Gates, Luis Silverio e Mark Souza apareceram brevemente, mas nunca alcan\u00e7aram o estrelato.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Mesmo o Quiz n\u00e3o era uma coisa certa. Disse Wilson: \u201cN\u00e3o o vi indo para as grandes ligas\u201d.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">O question\u00e1rio foi dividido em 1976 entre Waterloo e AA Jacksonville. Ele passou todos os anos de 1977 e 1978 em Jacksonville e, aos 25 anos, parecia mais um preenchedor organizacional. Os Royals finalmente o transferiram para Omaha para a temporada de 1979, onde ele foi adequado, mas longe de ser espetacular.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Kansas City, sem armas de bullpen, relutantemente deu-lhe uma chance em julho de 1979. Ele fez sua estreia na liga principal em 8 de julho com 2\u2154 entradas de bola fechada contra o White Sox. Ele fez 32 apari\u00e7\u00f5es at\u00e9 o final do ver\u00e3o, lan\u00e7ando 40 entradas com um respeit\u00e1vel ERA de 3,15. Seu companheiro de equipe de longa data, George Brett, disse: &#8220;Nunca tinha ouvido falar dele. Ele parecia engra\u00e7ado, parecia engra\u00e7ado. Ele era engra\u00e7ado e eu queria saber por que n\u00e3o trocamos por algu\u00e9m&#8221;.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Durante o inverno, os Royals contrataram um novo t\u00e9cnico, Jim Frey. Frey olhou para a entrega de Quisenberry, que na \u00e9poca estava entre tr\u00eas quartos e arma de fogo. No treinamento de primavera, ele conectou Quiz com Kent Tekulve, que obteve grande sucesso em 1979 como submarinista. Tekulve ensinou a Quiz o estilo submarino, e o resto \u00e9 tradi\u00e7\u00e3o do beisebol.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Quiz liderou os campeonatos com 75 partidas em 1980, enquanto acumulou 33 defesas, o l\u00edder da liga, ajudando os Royals a alcan\u00e7ar sua primeira World Series.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Nas seis temporadas de 1980 a 1985, seria dif\u00edcil encontrar um arremessador substituto melhor do que Dan Quisenberry. Ele liderou o campeonato em defesas cinco vezes e em jogos finalizou outras quatro. E ele tamb\u00e9m n\u00e3o era apenas um arremessador de uma entrada. Durante esse per\u00edodo de seis anos, ele teve uma m\u00e9dia de 120 entradas por ano, com um m\u00e1ximo de 139 em 1983. Nenhuma m\u00fasica de entrada. Sem teatralidade. Apenas um homem humilde e engra\u00e7ado caminhando at\u00e9 o monte e induzindo bolas rasteiras.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Sua ERA durante esse per\u00edodo de seis anos foi de impressionantes 2,45. Quiz raramente levava algu\u00e9m para passear e geralmente mantinha a bola no parque. Ele nunca foi um grande atacante, mas seu lan\u00e7amento submarino induziu os rebatedores a bater a bola no ch\u00e3o, onde muitas vezes isso se transformava em uma jogada dupla que matava o inning. Quiz formou tr\u00eas times All-Star durante esse per\u00edodo, ao mesmo tempo que recebeu votos de Cy Young em cinco temporadas.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Ele terminou em segundo lugar na vota\u00e7\u00e3o de Cy Young em duas ocasi\u00f5es (1983-84) e em terceiro em outras duas temporadas. Ele obteve votos de MVP em cinco temporadas, com o terceiro lugar em 1984, quando salvou 44 jogos.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Suas 45 defesas em 1983 foram um recorde de uma \u00fanica temporada na \u00e9poca. Junto com os n\u00fameros de salvamento espalhafatosos, Quiz apareceu na maioria das maiores vit\u00f3rias dos Royals da \u00e9poca. Ele conseguiu a defesa no jogo 3 do ALCS de 1980, que colocou os Royals em sua primeira World Series. Ele conseguiu as finais dos jogos 6 e 7 do ALCS de 1985 contra os Blue Jays e conseguiu a vit\u00f3ria no jogo 6 da World Series, o infame Denkinger Game. Em 30 de abril de 1980, Quiz e o apanhador Jamie Quirk se tornaram a primeira bateria totalmente Q na hist\u00f3ria da liga principal.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">O tempo de Quiz como Royal chegou ao fim durante a temporada de 1988. Aos 35 anos, ele vivia com fuma\u00e7a, espelhos e ast\u00facia, mas ainda n\u00e3o estava pronto para desligar. Depois de ser dispensado pelos Royals, ele se reuniu com o ex-t\u00e9cnico Whitey Herzog por duas temporadas em St. Ele encerrou sua carreira com uma passagem de cinco jogos pelos Giants em 1990, antes que problemas no bra\u00e7o encerrassem sua ilustre carreira.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">O nome de Quiz ainda est\u00e1 no topo das listas de carreira dos Royals em categorias como ERA, caminhadas por nove entradas e ERA+ ajustado. Ele era o l\u00edder da carreira do time em defesas quando se aposentou antes de ser ultrapassado por Jeff Montgomery. Seu nome ainda est\u00e1 entre os 10 primeiros em v\u00e1rias categorias de carreira e temporada \u00fanica.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Al\u00e9m de ser um excelente arremessador, Quiz tamb\u00e9m era um engra\u00e7adinho residente e um not\u00e1vel poeta. Quando a realeza recebeu um telefonema de parab\u00e9ns do presidente Reagan ap\u00f3s a s\u00e9rie de 1985, Ron inadvertidamente chamou Dan de \u201cJim Quisenberry\u201d.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Quando a equipe visitou a Casa Branca, Reagan pediu desculpas pela gafe, ao que Quiz respondeu: \u201cTudo bem, Don\u201d.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Publicou um livro de poesia em 1998 chamado <em>Em dias como este<\/em>. \u00c9 muito bom.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\"><em>Eu estava olhando para cima quando Janie e eu tivemos uma menina e um menino<\/em><\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\"><em>Uma greve de cinquenta dias, disse Marvin Miller<\/em><\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\"><em>Vamos mostrar a eles nossos m\u00fasculos<\/em><\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\"><em>Aprendi a pendurar papel de parede<\/em><\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Na aposentadoria, Dan e sua amada esposa, Janie, estiveram ativamente envolvidos na comunidade de Kansas City. Eles fizeram o trabalho de um propriet\u00e1rio rural para o Harvesters Food Bank.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Em janeiro de 1998, durante f\u00e9rias para esquiar no Colorado, Quiz sentiu dores de cabe\u00e7a, tonturas e vis\u00e3o turva. Ao retornar ao KC, ele foi imediatamente ao m\u00e9dico e foi diagnosticado com astrocitoma em est\u00e1gio IV, uma forma altamente maligna de c\u00e2ncer no c\u00e9rebro. A cirurgia e o tratamento n\u00e3o conseguiram salvar o homem que salvou tantos jogos. Perdemo-lo em 30 de setembro de 1998, aos 45 anos.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Nos \u00faltimos anos, tem havido um esfor\u00e7o, e com raz\u00e3o, para que o Hall da Fama d\u00ea uma nova olhada no corpo da obra de Dan.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Aqui estamos em 2026, e a maioria dos eleitores ainda n\u00e3o sabe como avaliar adequadamente os arremessadores substitutos. O arremessador mais frequentemente comparado ao Quiz foi seu contempor\u00e2neo Bruce Sutter, eleito para o Hall em 2006.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">N\u00e3o estou tirando nada de Sutter, que era um arremessador fant\u00e1stico, mas voc\u00ea n\u00e3o pode olhar para eles lado a lado e n\u00e3o defender o Quiz. Eles lan\u00e7aram quase um n\u00famero id\u00eantico de entradas e jogos. Sutter tem mais alguns salvamentos (300 a 244); O quiz tem um ERA melhor (2,76 a 2,83). Sutter chegou ao Hall com 24 WAR; O teste come\u00e7a \u00e0s 24h6.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Quiz ganhou o Rolaids Relief Award cinco vezes. Sutter venceu quatro vezes. Sutter tem um Cy Young, embora n\u00e3o por culpa de Quiz, que deveria ter vencido em 1983.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Tendo assistido ao lan\u00e7amento de Sutter e Quiz ao longo de suas carreiras, acredito que ambos s\u00e3o leg\u00edtimos membros do Hall da Fama.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\">Os Royals pelo menos acertaram, introduzindo Quiz no Hall da Fama do time em 30 de maio de 1998. Ele e Janie circularam pelo est\u00e1dio em um Corvette convers\u00edvel enquanto 30.341 f\u00e3s dos Royals derramavam seu amor sobre ele com uma ova\u00e7\u00e3o prolongada de p\u00e9.<\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\"><em>Principalmente eu estava de cabe\u00e7a baixa<\/em><\/p>\n<\/div>\n<div class=\"duet--article--article-body-component\">\n<p class=\"duet--article--dangerously-set-cms-markup duet--article--standard-paragraph _1upudxki _174s0un1 _174s0un0 _1mt21p01\"><em>Mas \u00e0s vezes eu olhei para cima<\/em><\/p>\n<\/div>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.royalsreview.com&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land \u2019 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando voc\u00ea ouve o nome Dan Quisenberry, qual a primeira coisa que vem \u00e0 sua mente? \u00c9 o seu fabuloso recorde de arremessos? \u00c9 a sua entrega submarina incomum? Poderia ser seu senso de humor perverso? Talvez seja o cabelo ruivo e o bigode de policial \/ estrela porn\u00f4 dos anos 70? Pode ser tudo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1826942,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[43],"tags":[],"class_list":["post-1826941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realeza"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1826941"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826941\/revisions"}],"predecessor-version":[{"id":1826943,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1826941\/revisions\/1826943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1826942"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1826941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1826941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1826941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}