{"id":1827009,"date":"2026-07-15T10:07:45","date_gmt":"2026-07-15T10:07:45","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827009"},"modified":"2026-07-15T10:07:45","modified_gmt":"2026-07-15T10:07:45","slug":"critica-do-filme-a-originalidade-nao-pode-salvar-gail-daughtry-and-the-celebrity-sex-pass-the-news-herald","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/critica-do-filme-a-originalidade-nao-pode-salvar-gail-daughtry-and-the-celebrity-sex-pass-the-news-herald\/","title":{"rendered":"Cr\u00edtica do filme: A originalidade n\u00e3o pode salvar &#8216;Gail Daughtry and the Celebrity Sex Pass&#8217; \u2013 The News Herald"},"content":{"rendered":"<figure><\/figure>\n<\/p>\n<div>\n<p>Existe realmente um passe sexual para celebridades? \u00c9 um aparente acordo entre dois amantes de que cada um pode escolher uma celebridade para fazer sexo (se tiver oportunidade) sem violar o relacionamento. N\u00e3o me pergunte se \u00e9 uma pr\u00e1tica da vida real. Meu \u00fanico conhecimento disso \u00e9 encontrado no filme atual \u201cGail Daughtry and the Celebrity Sex Pass\u201d, estrelado por Zoe Deutch no papel-t\u00edtulo.<\/p>\n<p>Gail \u00e9 uma cabeleireira rural do Kansas que est\u00e1 noiva de seu namorado, Tom (interpretado por Michael Cassidy), e faltam duas semanas para o casamento. Tom explica a Gail o arranjo de um passe sexual para celebridades e escolhe a atriz brit\u00e2nica Tilda Swinton. Por sua vez, Gail escolhe Jon Hamm, do famoso Madmen (que interpreta a si mesmo). Mas quando o casal vai a uma sess\u00e3o de aut\u00f3grafos com Jennifer Aniston (que interpreta a si mesma), Tom decide escolher a Sra. Aniston como seu passe sexual para celebridades, em vez da Sra.<\/p>\n<p>Veja s\u00f3, Tom consegue um encontro sexual com a Sra. Aniston no local da sess\u00e3o de aut\u00f3grafos do livro. Gail os descobre e \u00e9 uma cena embara\u00e7osa. Ou \u00e9? Nossos padr\u00f5es de comportamento s\u00e3o agora t\u00e3o baixos que o sexo \u00e9 t\u00e3o casual? Escrito e dirigido por David Wain, o filme \u00e9 uma celebra\u00e7\u00e3o do hedonismo.<\/p>\n<p>Zangada com o noivo, Gail decide ir a uma conven\u00e7\u00e3o de cabeleireiros em Los Angeles com Otto, seu melhor amigo e colega de trabalho no sal\u00e3o. Ao chegarem ao aeroporto de Los Angeles, a pasta de Gail \u00e9 levada por engano por dois vil\u00f5es enquanto ela toma posse da pasta deles (que cont\u00e9m documentos do governo e planos para induzir quebras no mercado mundial). Isso se transforma na subtrama do passe sexual.<\/p>\n<p>Seguindo o conselho da vidente Charlotte (interpretada por Kerri Kenney-Silver), Gail decide igualar as contas com Tom e buscar seu passe sexual com Jon Hamm. Gail e Otto v\u00e3o \u00e0 ag\u00eancia de Hamm, onde conhecem o aspirante a agente Caleb (interpretado por Ben Wang). Embora Caleb n\u00e3o seja capaz de produzir Jon Hamm, ele concorda em ajudar a dupla (apenas para ser demitido da ag\u00eancia de talentos). Mas Caleb tamb\u00e9m consegue roubar o \u00faltimo endere\u00e7o conhecido de Hamm de um arquivo da ag\u00eancia e o trio segue o exemplo.<\/p>\n<p>Acontece que Hamm havia se mudado para outro local um ano antes. A casa agora \u00e9 ocupada por \u201cWeird Al\u201d Yankovic (que interpreta ele mesmo). Isso os leva ao fot\u00f3grafo Vincent (Ken Marino), cuja ambi\u00e7\u00e3o de longa data \u00e9 conseguir uma foto de Jon Hamm (o que ele n\u00e3o conseguiu fazer uma d\u00e9cada antes, o que o levou a ser demitido da People Magazine). Vincent se junta ao trio e eles seguem uma pista que acaba em um bairro sem sa\u00edda.<\/p>\n<p>Mas n\u00e3o \u00e9 uma perda total. Morando neste bairro est\u00e1 John Slattery (que estrelou com Hamm em Madmen e que tamb\u00e9m interpreta a si mesmo). Slattery os leva at\u00e9 a resid\u00eancia de Hamm. O assistente de Hamm oferece-lhes acesso ao ator com a condi\u00e7\u00e3o de que forne\u00e7am a Hamm uma ideia s\u00f3lida para um filme.<\/p>\n<p>Lembre-se do interruptor da pasta. O grupo olha dentro da pasta do carro e descobre que n\u00e3o \u00e9 de Gail. O mais importante \u00e9 que descobriram os documentos pertencentes \u00e0 sinistra Ludovica (interpretada por Sabrina Imacciatore). O grupo descobre essa conspira\u00e7\u00e3o e tem a ideia de que daria um \u00f3timo roteiro de filme. Enquanto isso, Ludovica e seus capangas perseguem Gail.<\/p>\n<p>O grupo supera a gangue de Ludovica e volta para a resid\u00eancia de Hamm. Embora Hamm n\u00e3o esteja interessado na ideia do filme, ele estende favores ao grupo, incluindo a disposi\u00e7\u00e3o de ser o passe sexual de celebridade de Gail. Se tudo isso \u00e9 demais para voc\u00ea, n\u00e3o se sinta mal. \u00c9 demais para mim tamb\u00e9m. \u201cGail Daughtry and the Celebrity Sex Pass\u201d \u00e9 uma celebra\u00e7\u00e3o do comportamento degenerado (n\u00e3o muito diferente daquele exibido quando a Sra. Aniston estrelou Friends).<\/p>\n<p>Escusado ser\u00e1 dizer que este n\u00e3o \u00e9 um filme de fam\u00edlia. Mas tamb\u00e9m \u00e9 uma situa\u00e7\u00e3o lament\u00e1vel se \u201cGail Daughtry and the Celebrity Sex Pass\u201d se conecta com adultos (cujos padr\u00f5es s\u00e3o imitados por seus filhos e filhas).<\/p>\n<p><em>John O&#8217;Neill, de Allen Park, escreve uma cr\u00edtica semanal.<\/em><\/p>\n<\/p>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.thenewsherald.com&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land \u2019 <\/em>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Existe realmente um passe sexual para celebridades? \u00c9 um aparente acordo entre dois amantes de que cada um pode escolher uma celebridade para fazer sexo (se tiver oportunidade) sem violar o relacionamento. N\u00e3o me pergunte se \u00e9 uma pr\u00e1tica da vida real. Meu \u00fanico conhecimento disso \u00e9 encontrado no filme atual \u201cGail Daughtry and the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-1827009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827009"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827009\/revisions"}],"predecessor-version":[{"id":1827011,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827009\/revisions\/1827011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827010"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}