{"id":1827157,"date":"2026-07-15T12:39:24","date_gmt":"2026-07-15T12:39:24","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827157"},"modified":"2026-07-15T12:39:24","modified_gmt":"2026-07-15T12:39:24","slug":"neymar-cancela-festa-de-1-ano-da-filha-mel-e-motivo-surpreende-fas-apos-polemica-na-internet-%f0%9f%9a%a8","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/neymar-cancela-festa-de-1-ano-da-filha-mel-e-motivo-surpreende-fas-apos-polemica-na-internet-%f0%9f%9a%a8\/","title":{"rendered":"Neymar cancela festa de 1 ano da filha Mel e motivo surpreende f\u00e3s ap\u00f3s pol\u00eamica na internet \ud83d\udea8"},"content":{"rendered":"<p><iframe loading=\"lazy\"  width=\"580\" height=\"385\" src=\"https:\/\/www.youtube.com\/embed\/kXRPu-SfFbk?autoplay=1&#038;modestbranding=1\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<br \/>\ud83d\udea8 NEYMAR JR. surpreendeu ao cancelar a grande festa preparada para comemorar o primeiro anivers\u00e1rio da filha MEL, fruto do relacionamento com BRUNA BIANCARDI.<\/p>\n<p>Segundo informa\u00e7\u00f5es divulgadas pela imprensa, a comemora\u00e7\u00e3o teria atra\u00e7\u00f5es como personagens das Princesas da Disney e efeitos especiais, mas o jogador decidiu mudar os planos.<\/p>\n<p>No lugar da festa luxuosa, a fam\u00edlia realizou um churrasco reservado na casa onde estava hospedada nos Estados Unidos durante a Copa do Mundo.<\/p>\n<p>\ud83d\udcf8 BRUNA BIANCARDI compartilhou registros do momento nas redes sociais, mostrando as crian\u00e7as brincando, uma decora\u00e7\u00e3o delicada inspirada em abelhas e um ambiente familiar.<\/p>\n<p>A mudan\u00e7a aconteceu logo ap\u00f3s a elimina\u00e7\u00e3o da Sele\u00e7\u00e3o Brasileira no Mundial. Depois da viagem, Neymar deve retornar ao Brasil e passar alguns dias com a fam\u00edlia em sua mans\u00e3o em Mangaratiba.<\/p>\n<p>\ud83d\udcac Na internet, alguns elogiaram a simplicidade da comemora\u00e7\u00e3o, enquanto outros se perguntaram o motivo da mudan\u00e7a de planos.<\/p>\n<p>#Neymar #BrunaBiancardi #Mel #Famosos #Celebridades #Anivers\u00e1rio #CopaDoMundo #YouTubeShorts #Shorts #Viral<br \/>\n<br \/><a href=\"https:\/\/www.youtube.com\/watch?v=kXRPu-SfFbk\">Video Source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udea8 NEYMAR JR. surpreendeu ao cancelar a grande festa preparada para comemorar o primeiro anivers\u00e1rio da filha MEL, fruto do relacionamento com BRUNA BIANCARDI. Segundo informa\u00e7\u00f5es divulgadas pela imprensa, a comemora\u00e7\u00e3o teria atra\u00e7\u00f5es como personagens das Princesas da Disney e efeitos especiais, mas o jogador decidiu mudar os planos. No lugar da festa luxuosa, a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1827158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[44],"tags":[],"class_list":["post-1827157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827157"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827157\/revisions"}],"predecessor-version":[{"id":1827159,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827157\/revisions\/1827159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827158"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}