{"id":1827198,"date":"2026-07-15T13:12:23","date_gmt":"2026-07-15T13:12:23","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827198"},"modified":"2026-07-15T13:12:23","modified_gmt":"2026-07-15T13:12:23","slug":"jack-whitehall-brinca-sobre-ter-vindo-para-o-emprego-de-gordon-ramsay","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/jack-whitehall-brinca-sobre-ter-vindo-para-o-emprego-de-gordon-ramsay\/","title":{"rendered":"Jack Whitehall brinca sobre ter vindo para o emprego de Gordon Ramsay"},"content":{"rendered":"<figure><\/figure>\n<\/p>\n<div>\n<p><strong>Jack Whitehall<\/strong> est\u00e1 vindo para <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.usmagazine.com\/celebrities\/gordon-ramsay\/\"><strong>Gordon Ramsay<\/strong><\/a>reinado na Fox &#8211; e ele tem grandes esperan\u00e7as de que seu <em>O mais idiota da na\u00e7\u00e3o<\/em> hospedar um show levar\u00e1 a mais oportunidades.<\/p>\n<p>\u201cTive alguma satisfa\u00e7\u00e3o em encerrar meu amigo Gordon Ramsay porque finalmente a Fox havia encomendado um programa do qual ele n\u00e3o fazia parte e que eu estava vindo para sua coroa como o rosto da Fox\u201d, brincou Whitehall, 38, durante uma entrevista exclusiva com <em>N\u00f3s semanalmente<\/em>. \u201cE voc\u00ea provavelmente pode adivinhar o que ele me disse.\u201d<\/p>\n<p>Whitehall estava entusiasmado com a oportunidade de <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.usmagazine.com\/entertainment\/news\/fox-fall-schedule-for-new-returning-tv-shows-doc-special-forces\/\">apresentar seu pr\u00f3prio show.<\/a><\/p>\n<p>&#8220;Tenho que usar muitos pap\u00e9is neste programa. Sou o mestre do question\u00e1rio, mas \u00e0s vezes tamb\u00e9m sou mais como o conselheiro escolar, onde tento dar-lhes um ombro para chorar&#8221;, observou ele. \u201cOu um abra\u00e7o de apoio quando mais precisam.\u201d<\/p>\n<div class=\"link-related article link-related__with-thumb\">\n\t\t\t<a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" class=\"article__thumbnail related-ab-test\" href=\"https:\/\/www.usmagazine.com\/entertainment\/news\/summer-tv-preview-2025-love-island-the-bear-and-more\/\" data-source=\"01\"><\/p>\n<figure class=\"article__figure\">\n<div class=\"ratio-based-placeholder\"><\/div>\n<\/figure>\n<p>\t\t<\/a><\/p>\n<div class=\"article__content\">\n<h3 class=\"article__title\">\n\t\t\t<a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" class=\"article__title-link related-ab-test\" href=\"https:\/\/www.usmagazine.com\/entertainment\/news\/summer-tv-preview-2025-love-island-the-bear-and-more\/\" data-source=\"01\"><br \/>\n    <span class=\"related-badge\">Relacionado: <\/span><span class=\"related-title\">Pr\u00e9via da TV de ver\u00e3o de 2025: por dentro de programas novos e recorrentes imperd\u00edveis<\/span><\/a><br \/>\n\t\t<\/h3>\n<\/p>\n<\/div>\n<p>\t\t\tClaro, todo mundo gosta de sair no ver\u00e3o. Mas a vida ao ar livre n\u00e3o parecer\u00e1 t\u00e3o boa quando voc\u00ea perceber o que o espera na telinha nesta temporada. Para come\u00e7ar, voc\u00ea obter\u00e1 respostas para alguns grandes obst\u00e1culos, como: O que exatamente aquela cr\u00edtica do restaurante disse sobre o favorito dos f\u00e3s do Hulu, The Bear &#8211; e [\u2026]\t\t<\/p>\n<\/div>\n<p>Ele continuou: \u201cEnt\u00e3o, em outros momentos, sou mais como o torturador. Estou realmente colocando-os em risco. Tive que ser muito valioso para tentar dar apoio \u00e0s vezes. Escolhi meus momentos\u201d.<\/p>\n<p><a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.usmagazine.com\/celebrity-news\/news\/elle-king-found-out-shes-autistic-after-nations-dumbest\/\"><em>O mais idiota da na\u00e7\u00e3o<\/em> \u00e9 descrito<\/a> como \u201cum formato comprovado em v\u00e1rios territ\u00f3rios internacionais, canaliza o esp\u00edrito escolar interno das celebridades enquanto elas voltam para a escola de ver\u00e3o, enfrentando uma mistura de tarefas desafiadoras, desafios f\u00edsicos em ritmo acelerado e conhecimentos de sala de aula h\u00e1 muito enterrados\u201d.<\/p>\n<figure class=\"wp-caption \">\n<div class=\"ratio-based-placeholder\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large credit-added wp-image-4355585\" src=\"https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1000&amp;quality=70&amp;strip=all\" alt=\"Veja como a Fox faz celebridades competindo para ver se s\u00e3o as \u2018mais burras da na\u00e7\u00e3o\u2019\" width=\"1000\" height=\"1263\" srcset=\"https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=100&amp;quality=86&amp;strip=all 100w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=200&amp;quality=55&amp;strip=all 200w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=300&amp;quality=55&amp;strip=all 300w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=400&amp;quality=40&amp;strip=all 400w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=500&amp;quality=86&amp;strip=all 500w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=600&amp;quality=40&amp;strip=all 600w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=700&amp;quality=40&amp;strip=all 700w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=800&amp;quality=40&amp;strip=all 800w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=900&amp;quality=62&amp;strip=all 900w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1000&amp;quality=70&amp;strip=all 1000w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1200&amp;quality=70&amp;strip=all 1200w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1400&amp;quality=86&amp;strip=all 1400w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1600&amp;quality=55&amp;strip=all 1600w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1800&amp;quality=86&amp;strip=all 1800w, https:\/\/www.usmagazine.com\/wp-content\/uploads\/2026\/06\/ND_Yearbook_final.jpeg?w=1920&amp;quality=86&amp;strip=all 1920w\" \/><\/div><figcaption class=\"wp-caption-text\"><span class=\"credit\">Brendan Meadows \/ FOX<\/span><\/figcaption><\/figure>\n<p>De acordo com a descri\u00e7\u00e3o, a cada semana \u201cas celebridades &#8216;mais inteligentes&#8217; se formam, estreitando o campo at\u00e9 que um exame final de alto risco determine quem ficar\u00e1 com a distin\u00e7\u00e3o que ningu\u00e9m deseja &#8211; o t\u00edtulo de The Nation&#8217;s Dumbest\u201d.<\/p>\n<p>\u201cAcho que estaria bastante envolvido [the show if I was a contestant]. N\u00e3o tenho muito conhecimento geral&#8221;, disse Whitehall \u00e0 Us. &#8220;E tenho alguns pontos cegos evidentes &#8211; principalmente na cultura pop e no esporte americanos. Eu poderia me desfazer em um programa como esse.\u201d<\/p>\n<p>Whitehall brincou que ele \u00e9 \u201cuma flor muito delicada\u201d, acrescentando: \u201cN\u00e3o acho que teria a resili\u00eancia para me colocar no programa&#8230; Eu n\u00e3o era particularmente acad\u00eamico. [in school]. Eu gostava mais de artes e teatro &#8211; mais como um garoto de teatro. Eu n\u00e3o era \u00f3timo academicamente, mas acho que as pessoas apenas fazem suposi\u00e7\u00f5es sobre mim porque tenho essa voz e pare\u00e7o bastante inteligente.\u201d<\/p>\n<p>O comediante<a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.usmagazine.com\/celebrity-news\/news\/andrew-yang-hopes-trump-watches-him-on-nations-dumbest\/\"> usou isso a seu favor<\/a> sobre <em>O mais idiota da na\u00e7\u00e3o<\/em>.<\/p>\n<p>\u201cNo programa, consigo parecer bastante presun\u00e7oso e acima de tudo\u201d, ele compartilhou. \u201cMas acho que \u00e9 s\u00f3 porque tenho um sotaque brit\u00e2nico sofisticado e todas as respostas escritas em uma prancheta na minha frente.\u201d<\/p>\n<p>Whitehall tamb\u00e9m aprendeu algumas li\u00e7\u00f5es importantes para o futuro. \u201c\u00c0s vezes voc\u00ea s\u00f3 precisa se controlar e dizer: &#8216;N\u00e3o seja t\u00e3o idiota&#8217;\u201d, disse ele. \u201cPorque \u00e9 muito dif\u00edcil. \u00c9 muito f\u00e1cil ficar parado ali e ser presun\u00e7oso e indiferente quando voc\u00ea tem todas as respostas escritas. Eu sempre tive que me lembrar que se a bota tivesse sido do outro lado, eu estaria me debatendo e fazendo perguntas erradas. Tentei ter certeza de que tamb\u00e9m seria compassivo.\u201d<\/p>\n<p>Felizmente, Whitehall <a rel=\"nofollow\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.usmagazine.com\/entertainment\/news\/foxs-nations-dumbest-show-questions-celebrity-intelligence\/\">n\u00e3o precisava participar<\/a> em responder perguntas junto com a turma de estrelas que inclui personalidades de TV <strong>Hilaria Baldwin<\/strong>atriz<strong> Carmem Eletra<\/strong>ator <strong>Antonio Michael Hall<\/strong>ator <strong>Jon Heder<\/strong>m\u00fasico <strong>Chase Hudson<\/strong> e rapper <strong>Gelo-T<\/strong>.<\/p>\n<div id=\"news-block\">\n<div class=\"newsletter-form  \">\n\t<img decoding=\"async\" src=\"https:\/\/www.usmagazine.com\/wp-content\/themes\/us-weekly\/assets\/img\/newsletter-bg-narrow.jpg\" alt=\"\" class=\"newsletter-form__background background-narrow\" loading=\"lazy\" \/><br \/>\n\t<img decoding=\"async\" src=\"https:\/\/www.usmagazine.com\/wp-content\/themes\/us-weekly\/assets\/img\/newsletter-bg-wide.jpg\" alt=\"\" class=\"newsletter-form__background background-wide\" loading=\"lazy\" \/><\/p>\n<div class=\"newsletter-signup__success\" aria-live=\"polite\">\n<h3>Obrigado!<\/h3>\n<p>Voc\u00ea se inscreveu com sucesso.<\/p>\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Cantor e compositor <strong>Ela King<\/strong>ex-quarterback da NFL <strong>Matt Leinar<\/strong>t, personalidade de TV e m\u00e9dico<strong> Dr. Drew Pinsky<\/strong> tamb\u00e9m fazem parte do grupo enquanto <em>Idiota<\/em> estrela <strong>Steve-O<\/strong>cantor <strong>JoJo Siwa<\/strong> e ex-candidato presidencial <strong>Andr\u00e9 Yang<\/strong> completar o elenco.<\/p>\n<p>\u201c[In season 2 we could have] talvez alguns outros membros da fam\u00edlia Fox participem\u201d, sugeriu Whitehall a <em>N\u00f3s<\/em>. &#8220;Ken Young, Joel McHale, Rob Lowe, Ernest Leary, eles seriam bons. Gordon Ramsay &#8211; eu adoraria ver Ramsay nisso.&#8221;<\/p>\n<p><em>O mais idiota da na\u00e7\u00e3o<\/em> estreia na Fox na quarta-feira, 15 de julho, \u00e0s 21h (hor\u00e1rio do leste dos EUA).<\/p>\n<\/p>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.usmagazine.com&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land \u2019 <\/em>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jack Whitehall est\u00e1 vindo para Gordon Ramsayreinado na Fox &#8211; e ele tem grandes esperan\u00e7as de que seu O mais idiota da na\u00e7\u00e3o hospedar um show levar\u00e1 a mais oportunidades. \u201cTive alguma satisfa\u00e7\u00e3o em encerrar meu amigo Gordon Ramsay porque finalmente a Fox havia encomendado um programa do qual ele n\u00e3o fazia parte e que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-1827198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827198"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827198\/revisions"}],"predecessor-version":[{"id":1827200,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827198\/revisions\/1827200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827199"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}