{"id":1827220,"date":"2026-07-15T13:31:44","date_gmt":"2026-07-15T13:31:44","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827220"},"modified":"2026-07-15T13:31:44","modified_gmt":"2026-07-15T13:31:44","slug":"a-terceira-selecao-all-star-consecutiva-de-bobby-witt-jr-coloca-os-royals-no-relogio","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/a-terceira-selecao-all-star-consecutiva-de-bobby-witt-jr-coloca-os-royals-no-relogio\/","title":{"rendered":"A terceira sele\u00e7\u00e3o All-Star consecutiva de Bobby Witt Jr. coloca os Royals no rel\u00f3gio"},"content":{"rendered":"<figure><\/figure>\n<\/p>\n<div><!--qv q:key=QW_6--><!--qv q:id=5i q:key=vcaa:\n\n\n\n<p>O Kansas City Royals tem Bobby Witt Jr. como uma verdadeira estrela, mas o beisebol \u00e9 um esporte coletivo e \u00e9 preciso muita gente para ter sucesso. Como tal, e dado o seu estatuto de pequeno mercado,<a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/royals-have-a-chance-to-correct-a-long-forgotten-mistake-with-foster-griffin-01kxejs2t2v0\"> especula\u00e7\u00f5es e rumores <\/a>sempre far\u00e1 parte da equa\u00e7\u00e3o.<\/p>\n\n\n\n--><!--qv q:id=5j q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-0\" class=\"mt-[18px] md:mt-0 mb-[18px] [&amp;_a]:text-secondary my-f-1\">O Kansas City Royals tem Bobby Witt Jr. como uma verdadeira estrela, mas o beisebol \u00e9 um esporte coletivo e \u00e9 preciso muita gente para ter sucesso. Como tal, e dado o seu estatuto de pequeno mercado,<a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/royals-have-a-chance-to-correct-a-long-forgotten-mistake-with-foster-griffin-01kxejs2t2v0\"> especula\u00e7\u00f5es e rumores <\/a>sempre far\u00e1 parte da equa\u00e7\u00e3o.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=5l q:key=vcaa:\n\n\n\n<p>Witt acabou de ganhar seu <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/two-royals-voted-into-the-2026-all-star-game-despite-poor-record-01kwsnb61nvm\">terceira sele\u00e7\u00e3o All-Star consecutiva<\/a>. Ele j\u00e1 fez parte do primeiro time consecutivo da MLB e ganhou dois pr\u00eamios Gold Glove e Silver Slugger. Salvo uma reviravolta chocante, ele adicionar\u00e1 mais \u00e0 sua contagem no final desta temporada.<\/p>\n\n\n\n--><!--qv q:id=5m q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-1\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">Witt acabou de ganhar seu <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/two-royals-voted-into-the-2026-all-star-game-despite-poor-record-01kwsnb61nvm\">terceira sele\u00e7\u00e3o All-Star consecutiva<\/a>. Ele j\u00e1 fez parte do primeiro time consecutivo da MLB e ganhou dois pr\u00eamios Gold Glove e Silver Slugger. Salvo uma reviravolta chocante, ele adicionar\u00e1 mais \u00e0 sua contagem no final desta temporada.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=5o q:key=vcaa:\n\n\n\n<p>No entanto, o excelente jogo de Witt n\u00e3o ajudou muito a sua equipa. O Royals alcan\u00e7ou o intervalo do All-Star com um recorde de 38-59 e o quinto lugar no AL Central. \u00c9 por isso que s\u00f3 podemos imaginar quanto tempo levar\u00e1 para <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/adding-proven-star-talent-next-to-bobby-witt-jr-should-be-royals-priority-at-trade-deadline-01kwa32zh3bm\">Witt para for\u00e7ar sua sa\u00edda<\/a>.<\/p>\n\n\n\n--><!--qv q:id=5p q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-2\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">No entanto, o excelente jogo de Witt n\u00e3o ajudou muito a sua equipa. O Royals alcan\u00e7ou o intervalo do All-Star com um recorde de 38-59 e o quinto lugar no AL Central. \u00c9 por isso que s\u00f3 podemos imaginar quanto tempo levar\u00e1 para <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/adding-proven-star-talent-next-to-bobby-witt-jr-should-be-royals-priority-at-trade-deadline-01kwa32zh3bm\">Witt para for\u00e7ar sua sa\u00edda<\/a>.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=5r q:key=vcaa:\n\n\n\n<h2>Os Royals devem fazer o certo por Bobby Witt Jr. antes que seja tarde demais <\/h2>\n\n\n\n--><!--qv q:id=5s q:key=lY4S:mL_1--><\/p>\n<h2 id=\"inline-text-3\" class=\"scroll-mt-24 my-[18px] [&amp;_a]:text-secondary my-f-1\">Os Royals devem fazer o certo por Bobby Witt Jr. antes que seja tarde demais <\/h2>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=5u q:key=vcaa:\n\n\n\n<p>J\u00e1 vimos essa hist\u00f3ria in\u00fameras vezes antes. Um superstar se compromete com uma equipe de pequeno mercado, apenas para ver seus primeiros anos serem desperdi\u00e7ados. O sucesso individual \u00e9 bom e tudo, mas os verdadeiros concorrentes querem vencer no mais alto n\u00edvel.<\/p>\n\n\n\n--><!--qv q:id=5v q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-4\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">J\u00e1 vimos essa hist\u00f3ria in\u00fameras vezes antes. Um superstar se compromete com uma equipe de pequeno mercado, apenas para ver seus primeiros anos serem desperdi\u00e7ados. O sucesso individual \u00e9 bom e tudo, mas os verdadeiros concorrentes querem vencer no mais alto n\u00edvel.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=5x q:key=vcaa:\n\n\n\n<p>Witt assinou um mamute <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/www.spotrac.com\/mlb\/player\/_\/id\/30400\/bobby-witt-jr\">Contrato de 11 anos e US$ 288,8 milh\u00f5es<\/a> isso poderia se tornar um acordo de 14 anos e US$ 377 milh\u00f5es, dependendo das op\u00e7\u00f5es no final do pacto. Claramente, a jovem estrela est\u00e1 comprometida com a organiza\u00e7\u00e3o e a comunidade, mas isso n\u00e3o pode durar muito tempo.<\/p>\n\n\n\n--><!--qv q:id=5y q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-5\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">Witt assinou um mamute <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/www.spotrac.com\/mlb\/player\/_\/id\/30400\/bobby-witt-jr\">Contrato de 11 anos e US$ 288,8 milh\u00f5es<\/a> isso poderia se tornar um acordo de 14 anos e US$ 377 milh\u00f5es, dependendo das op\u00e7\u00f5es no final do pacto. Claramente, a jovem estrela est\u00e1 comprometida com a organiza\u00e7\u00e3o e a comunidade, mas isso n\u00e3o pode durar muito tempo.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=60 q:key=vcaa:\n\n\n\n<p>Tecnicamente, os Royals ainda podem mudar as coisas nesta temporada. Eles jogam em uma das divis\u00f5es mais fracas do beisebol e podem voltar aos trilhos com os movimentos certos antes do prazo final de negocia\u00e7\u00e3o de 3 de agosto, especialmente devido ao seu <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/royals-are-hedging-their-bets-on-seth-lugo-ahead-of-trade-deadline-01kx6g3ycge9\">relut\u00e2ncia em negociar Seth Lugo <\/a>e Michael Wacha. <\/p>\n\n\n\n--><!--qv q:id=61 q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-6\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">Tecnicamente, os Royals ainda podem mudar as coisas nesta temporada. Eles jogam em uma das divis\u00f5es mais fracas do beisebol e podem voltar aos trilhos com os movimentos certos antes do prazo final de negocia\u00e7\u00e3o de 3 de agosto, especialmente devido ao seu <a target=\"_blank\" target=\"_blank\" href=\"https:\/\/kckingdom.com\/royals-are-hedging-their-bets-on-seth-lugo-ahead-of-trade-deadline-01kx6g3ycge9\">relut\u00e2ncia em negociar Seth Lugo <\/a>e Michael Wacha. <\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=63 q:key=vcaa:\n\n\n\n<p>O gerente geral JJ Picollo tamb\u00e9m pode decidir ficar parado e se reagrupar na entressafra, mas ele e sua equipe de front office devem elaborar um plano para maximizar seu shortstop de 26 anos. Caso contr\u00e1rio, eles est\u00e3o prestando um p\u00e9ssimo servi\u00e7o a um dos jogadores mais talentosos a entrar na liga nas \u00faltimas d\u00e9cadas, e o que antes era um casamento feliz pode azedar rapidamente.<\/p>\n\n\n\n--><!--qv q:id=64 q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-7\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">O gerente geral JJ Picollo tamb\u00e9m pode decidir ficar parado e se reagrupar na entressafra, mas ele e sua equipe de front office devem elaborar um plano para maximizar seu shortstop de 26 anos. Caso contr\u00e1rio, eles est\u00e3o prestando um p\u00e9ssimo servi\u00e7o a um dos jogadores mais talentosos a entrar na liga nas \u00faltimas d\u00e9cadas, e o que antes era um casamento feliz pode azedar rapidamente.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=66 q:key=vcaa:\n\n\n\n<p>As carreiras passam r\u00e1pido e Witt pode acabar no territ\u00f3rio de Mike Trout se os Royals continuarem a desperdi\u00e7ar seus talentos. Negoci\u00e1-lo seria complicado, dado o seu sal\u00e1rio cada vez maior, que ultrapassar\u00e1 os 30 milh\u00f5es de d\u00f3lares em 2028 e continuar\u00e1 a aumentar at\u00e9 2034. E se formos honestos, negociar com Witt apenas iria incensar uma base de f\u00e3s t\u00e3o dedicada e poderia at\u00e9 causar diverg\u00eancias dentro do vesti\u00e1rio.<\/p>\n\n\n\n--><!--qv q:id=67 q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-8\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">As carreiras passam r\u00e1pido e Witt pode acabar no territ\u00f3rio de Mike Trout se os Royals continuarem a desperdi\u00e7ar seus talentos. Negoci\u00e1-lo seria complicado, dado o seu sal\u00e1rio cada vez maior, que ultrapassar\u00e1 os 30 milh\u00f5es de d\u00f3lares em 2028 e continuar\u00e1 a aumentar at\u00e9 2034. E se formos honestos, negociar com Witt apenas iria incensar uma base de f\u00e3s t\u00e3o dedicada e poderia at\u00e9 causar diverg\u00eancias dentro do vesti\u00e1rio.<\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:key=QW_6--><!--qv q:id=69 q:key=vcaa:\n\n\n\n<p>Mais uma vez, Witt foi o \u00fanico ponto positivo em Kansas City<a target=\"_blank\" target=\"_blank\" href=\"https:\/\/www.baseball-reference.com\/players\/w\/wittbo02.shtml\">cortando 0,286\/0,355\/0,461 <\/a>com 0,816 OPS, 103 rebatidas, 22 duplas, 13 home runs, 39 RBIs e 30 bases roubadas, l\u00edder da Liga Americana, e uma WAR de 4,9. Ele \u00e9 bom demais para ficar preso em um clube ruim, e jogadores de gera\u00e7\u00f5es merecem coisa melhor. <\/p>\n\n\n\n--><!--qv q:id=6a q:key=lY4S:mL_1--><\/p>\n<p id=\"inline-text-9\" class=\"my-[18px] [&amp;_a]:text-secondary my-f-1\">Mais uma vez, Witt foi o \u00fanico ponto positivo em Kansas City<a target=\"_blank\" target=\"_blank\" href=\"https:\/\/www.baseball-reference.com\/players\/w\/wittbo02.shtml\">cortando 0,286\/0,355\/0,461 <\/a>com 0,816 OPS, 103 rebatidas, 22 duplas, 13 home runs, 39 RBIs e 30 bases roubadas, l\u00edder da Liga Americana, e uma WAR de 4,9. Ele \u00e9 bom demais para ficar preso em um clube ruim, e jogadores de gera\u00e7\u00f5es merecem coisa melhor. <\/p>\n<p><!--\/qv--><!--\/qv--><!--\/qv--><!--qv q:id=6c q:key=1jXG:QW_7--><!--qv q:id=6d q:key=9yVI:Ef_0--><\/p>\n<div><!--qv q:s q:sref=6d q:key=--><\/p>\n<div data-testid=\"google-news-widget\" class=\"voltax-google-preferred-source my-5 p-4 flex items-center gap-4 rounded-lg bg-[#F0F0F0]\">\n<div class=\"flex min-w-0 flex-1 items-center gap-3\"><span class=\"font-group-big text-black text-[16px]\">Adicione-nos como fonte preferencial em <span class=\"font-bold\">Google<\/span><\/span><\/div>\n<p><a target=\"_blank\" target=\"_blank\" aria-label=\"Follow kckingdom.com on Google News\" href=\"https:\/\/www.google.com\/preferences\/source?q=kckingdom.com\" rel=\"noopener noreferrer\" class=\"flex h-[30px] w-[30px] shrink-0 items-center justify-center rounded-full bg-primary font-group-large text-sm font-medium text-white transition-colors hover:bg-secondary focus:bg-secondary md:w-auto md:gap-2.5 md:px-4 md:py-[5px]\"><span class=\"hidden pt-[1px] leading-[1.4] md:inline\">Seguir<\/span><\/a><\/div>\n<p><!--\/qv--><\/div>\n<p><!--\/qv--><!--\/qv--><\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte kckingdom.com&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land \u2019 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Kansas City Royals tem Bobby Witt Jr. como uma verdadeira estrela, mas o beisebol \u00e9 um esporte coletivo e \u00e9 preciso muita gente para ter sucesso. Como tal, e dado o seu estatuto de pequeno mercado, especula\u00e7\u00f5es e rumores sempre far\u00e1 parte da equa\u00e7\u00e3o. Witt acabou de ganhar seu terceira sele\u00e7\u00e3o All-Star consecutiva. Ele [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827221,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[43],"tags":[],"class_list":["post-1827220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realeza"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827220"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827220\/revisions"}],"predecessor-version":[{"id":1827222,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827220\/revisions\/1827222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827221"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}