{"id":1827451,"date":"2026-07-15T16:39:33","date_gmt":"2026-07-15T16:39:33","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827451"},"modified":"2026-07-15T16:39:33","modified_gmt":"2026-07-15T16:39:33","slug":"musicas-perdidas-de-david-bowie-de-1965-serao-lancadas-em-nova-compilacao","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/musicas-perdidas-de-david-bowie-de-1965-serao-lancadas-em-nova-compilacao\/","title":{"rendered":"M\u00fasicas perdidas de David Bowie de 1965 ser\u00e3o lan\u00e7adas em nova compila\u00e7\u00e3o"},"content":{"rendered":"\n<figure><\/figure>\n<\/p>\n<div id=\"post-957670\">\n<div class=\"featured-img\">\n<p>Cr\u00e9dito: Far Out \/ Alamy<\/p>\n<\/div>\n<div class=\"article-meta\">\n<div class=\"article-meta-left\">\n<p> <time datetime=\"2026-07-15T17:33:38+01:00\">Quarta, 15 de julho de 2026, 17h33, Reino Unido<\/time> <\/p>\n<\/p>\n<\/div>\n<\/div>\n<p>Um conjunto de in\u00e9ditos <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"http:\/\/faroutmagazine.co.uk\/tags\/david-bowie\" title=\"\">David Bowie<\/a> grava\u00e7\u00f5es de 1965 ser\u00e3o lan\u00e7adas em uma nova compila\u00e7\u00e3o.<\/p>\n<p>As faixas, que foram feitas com o produtor Shel Talmy quando Bowie ainda era conhecido como Davie Jones, aparecer\u00e3o em <em>As grava\u00e7\u00f5es de Shel Talmy<\/em>que chegar\u00e1 no dia 16 de setembro pela Parlophone.<\/p>\n<figure class=\"wp-block-grvmedia-grv-video GRVVideo GRVPrimisVideo\" \/>\n<p>Para provocar a pr\u00f3xima compila\u00e7\u00e3o, a faixa in\u00e9dita &#8216;I Want Your Love&#8217;, que \u00e9 uma das dez m\u00fasicas nunca antes ouvidas pelo p\u00fablico.<\/p>\n<p>O conjunto de faixas n\u00e3o apresenta apenas um Bowie pr\u00e9-fama. Tamb\u00e9m inclui contribui\u00e7\u00f5es de Jimmy Page quando ele era um pistoleiro de aluguel, como <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/faroutmagazine.co.uk\/pre-fame-david-bowie-met-jimmy-page-first-time\/\" title=\"The moment pre-fame David Bowie met Jimmy Page for the first time\">um m\u00fasico de sess\u00e3o<\/a> antes de ingressar no The Yardbirds e posteriormente formar o Led Zeppelin.<\/p>\n<p>Al\u00e9m disso, Nicky Hopkins, que tocaria piano em bandas como The Rolling Stones, tamb\u00e9m pode ser ouvido em <em>As grava\u00e7\u00f5es de Shel Talmy<\/em>.<\/p>\n<p>O historiador musical Alec Palao escreve sobre a compila\u00e7\u00e3o no encarte: &#8220;David Bowie, o artista, \u00e9 um livro de cap\u00edtulos, a virada de cada p\u00e1gina entregando algo completamente diferente e inesperado da anterior. E na leitura, um erro fundamental seria colocar qualquer um desses epis\u00f3dios contra os outros, quando na verdade cada fase fascinante de sua carreira deveria ser considerada complementar.&#8221;<\/p>\n<p>Paleo acrescenta: &#8220;Esta cole\u00e7\u00e3o, um cap\u00edtulo prim\u00e1rio, se n\u00e3o o primeiro, da jornada musical de David, merece considera\u00e7\u00e3o leg\u00edtima. \u00c9 invariavelmente tentador procurar pistas nas tentativas de in\u00edcio de um artista, e a juventude de Bowie foi dissecada mais do que a maioria, mas isso raramente foi feito dentro do contexto adequado.&#8221;<\/p>\n<p>Ele tamb\u00e9m afirma importantemente: &#8220;Os sons aqui n\u00e3o devem ser julgados pelos padr\u00f5es de sua carreira posterior, mas pelos padr\u00f5es do que estava acontecendo na Gr\u00e3-Bretanha naquele exato momento. Nesse caso, eles falam t\u00e3o alto da excita\u00e7\u00e3o de Londres e de sua cena musical naquele ano crucial de 1965 quanto do lan\u00e7amento de sua futura estrela mais brilhante&#8221;.<\/p>\n<p>Talmy, <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/faroutmagazine.co.uk\/shel-talmy-dead-at-87\/\" title=\"\">que morreu em 2024<\/a>j\u00e1 era um nome estabelecido a essa altura, tendo produzido &#8216;You Really Got Me&#8217;, do The Kinks, e &#8216;I Can&#8217;t Explain&#8217;, do The Who. Ele conheceu Bowie na Denmark Street, em Londres, o que os levou a unir for\u00e7as no est\u00fadio.<\/p>\n<p>Embora Bowie nunca tenha encontrado fama ou riqueza com seu nome de nascimento, Talmy comentou em 2017: &#8220;Achei que ele iria conseguir. A \u00fanica coisa lament\u00e1vel \u00e9 que ele e eu est\u00e1vamos cerca de seis anos \u00e0 frente do mercado&#8221;.<\/p>\n<p>Veja a tracklist completa e ou\u00e7a \u2018I Want Your Love\u2019 abaixo.<\/p>\n<h2 class=\"wp-block-heading\">David Bowie \u2013 <em>As grava\u00e7\u00f5es de Shel Talmy<\/em> lista de faixas:<\/h2>\n<ol>\n<li>&#8216;Voc\u00ea tem o h\u00e1bito de sair&#8217; (2026 Remaster) ^<\/li>\n<li>&#8216;Eu quero o seu amor&#8217; *^<\/li>\n<li>&#8216;Cupido&#8217; *^<\/li>\n<li>&#8216;Tenho pena do tolo&#8217; (remasteriza\u00e7\u00e3o de 2026) +<\/li>\n<li>&#8216;Baby Loves That Way&#8217; (Remasteriza\u00e7\u00e3o de 2026) ^<\/li>\n<li>&#8216;Keep Up With The Jones&#8217; (Instrumental) *^<\/li>\n<li>&#8216;Deixe ela comigo&#8217; *^<\/li>\n<li>&#8216;Eu vou te seguir&#8217; ^<\/li>\n<li>&#8216;Voc\u00ea tem que contar a ela&#8217; (remasteriza\u00e7\u00e3o de 2026) *^<\/li>\n<li>&#8216;Aceite minha dica&#8217; (remasteriza\u00e7\u00e3o de 2026) +<\/li>\n<li>&#8216;Certa Mulher&#8217; *^<\/li>\n<li>&#8216;Hoje&#8217; (Demonstra\u00e7\u00e3o) *-<\/li>\n<li>&#8216;Eu quero meu beb\u00ea de volta&#8217; (demonstra\u00e7\u00e3o) (remasteriza\u00e7\u00e3o de 2026) &#8211;<\/li>\n<li>&#8216;Eu vivo em sonhos&#8217; (demonstra\u00e7\u00e3o) *-<\/li>\n<li>&#8216;Bares da pris\u00e3o do condado&#8217; (demonstra\u00e7\u00e3o) &#8211;<\/li>\n<li>&#8216;\u00c9 a\u00ed que meu cora\u00e7\u00e3o est\u00e1&#8217; (demonstra\u00e7\u00e3o) (2026 Remaster) &#8211;<\/li>\n<li>&#8216;Eu acredito que te amo&#8217; (demonstra\u00e7\u00e3o) *-<\/li>\n<li>&#8216;You&#8217;ve Got A Habit Of Leaving&#8217; (overdub \/ vocal alternativo) (2026 Remaster) ^<\/li>\n<li>&#8216;I Pity The Fool&#8217; (tomada vocal alternativa) (2026 Remaster) +<\/li>\n<li>&#8216;Baby Loves That Way&#8217; (tomada vocal alternativa) *^<\/li>\n<li>&#8216;Take My Tip&#8217; (tomada vocal alternativa) (2026 Remaster) +<\/li>\n<\/ol>\n<p><strong>Chave<\/strong><\/p>\n<p>In\u00e9dito anteriormente *<br \/>Davie Jones e o ter\u00e7o inferior ^<br \/>Os meninos Manish +<br \/>David Jones \u2013<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\">\n<div class=\"jeg_video_container jeg_video_content\"><\/div>\n<\/figure>\n<div class=\"article-follow preferred-source\">\n<div class=\"article-sharing google-follow\"> <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" class=\"fw\" href=\"https:\/\/www.google.com\/preferences\/source?q=https:\/\/faroutmagazine.co.uk\/\"> <span>ADICIONAR COMO FONTE PREFERIDA NO GOOGLE<\/span> <img decoding=\"async\" width=\"28\" height=\"28\" src=\"https:\/\/faroutmagazine.co.uk\/wp-content\/themes\/far-out-magazine\/img\/google-discover.svg\" alt=\"\" \/> <\/a> <\/div>\n<\/div>\n<div id=\"incontent-container\">\n<div class=\"incontent-content\">\n<div>\n<div>\n<div>\n<h6>O boletim informativo de m\u00fasica Far Out<\/h6>\n<p>Todas as \u00faltimas not\u00edcias musicais da voz independente da cultura.<br \/>Direto para sua caixa de entrada.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte faroutmagazine.co.uk&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land   \u2019 Source Link <\/em><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Far Out \/ Alamy Quarta, 15 de julho de 2026, 17h33, Reino Unido Um conjunto de in\u00e9ditos David Bowie grava\u00e7\u00f5es de 1965 ser\u00e3o lan\u00e7adas em uma nova compila\u00e7\u00e3o. As faixas, que foram feitas com o produtor Shel Talmy quando Bowie ainda era conhecido como Davie Jones, aparecer\u00e3o em As grava\u00e7\u00f5es de Shel Talmyque chegar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1827451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827451"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827451\/revisions"}],"predecessor-version":[{"id":1827453,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827451\/revisions\/1827453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827452"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}