{"id":1827462,"date":"2026-07-15T16:47:57","date_gmt":"2026-07-15T16:47:57","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827462"},"modified":"2026-07-15T16:47:57","modified_gmt":"2026-07-15T16:47:57","slug":"de-olho-no-entretenimento-tom-cruise-abandona-a-personalidade-de-missao-impossivel","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/de-olho-no-entretenimento-tom-cruise-abandona-a-personalidade-de-missao-impossivel\/","title":{"rendered":"De olho no entretenimento: Tom Cruise abandona a personalidade de &#8216;Miss\u00e3o Imposs\u00edvel&#8217;"},"content":{"rendered":"\n<figure><\/figure>\n<\/p>\n<div id=\"\">\n<div class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Stack-vJ7SwH7U__StackBase-sc-1m5bkhd-0 gZIaF dsnUCb\">\n<p><h3 class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Heading-jchBxnCE__HeadingBase-sc-vsmc8c-0 dliKXD\">NOT\u00cdCIAS<\/h3>\n<hr class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Divider-3xbO3j9L__BaseDivider-sc-1qodjle-0 gdQkyi\" \/>\n<div class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Stack-vJ7SwH7U__StackBase-sc-1m5bkhd-0 evEXvX TYjjN\">\n<p><time datetime=\"2026-07-15T16:09:23.000Z\" class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Text-nO2aZ44r__TextBase-sc-s2hv5x-0 fwHEfg\">Publicado: <span class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Text-nO2aZ44r__TextBase-sc-s2hv5x-0 eizSVL\"><time datetime=\"2026-07-15T16:09:23.000Z\">15 de julho de 2026 \u00e0s 12h09<\/time><\/span><\/time><\/p>\n<\/div>\n<p class=\"Box-_wrDxHtU__Box-sc-10sa3ie-0 Text-nO2aZ44r__TextBase-sc-s2hv5x-0 coHFxg kVVZcY\">Tom Cruise est\u00e1 trocando sua personalidade de &#8216;Miss\u00e3o Imposs\u00edvel&#8217; para um novo papel&#8230; Um magnata do petr\u00f3leo idoso e amante de gatos! Al\u00e9m disso, a vida de Madonna recebe tratamento de quadrinhos. Gwen Baumgardner tem seu relat\u00f3rio Eye on Entertainment<\/p>\n<\/div>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.clickorlando.com&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land   \u2019 Source Link <\/em><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>NOT\u00cdCIAS Publicado: 15 de julho de 2026 \u00e0s 12h09 Tom Cruise est\u00e1 trocando sua personalidade de &#8216;Miss\u00e3o Imposs\u00edvel&#8217; para um novo papel&#8230; Um magnata do petr\u00f3leo idoso e amante de gatos! Al\u00e9m disso, a vida de Madonna recebe tratamento de quadrinhos. Gwen Baumgardner tem seu relat\u00f3rio Eye on Entertainment &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1827462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827462"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827462\/revisions"}],"predecessor-version":[{"id":1827464,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827462\/revisions\/1827464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827463"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}