{"id":1827543,"date":"2026-07-15T18:28:39","date_gmt":"2026-07-15T18:28:39","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827543"},"modified":"2026-07-15T18:28:39","modified_gmt":"2026-07-15T18:28:39","slug":"jalen-brunson-ingressara-no-estudio-inaugural-de-esportes-e-entretenimento-da-variety-em-nova-york","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/jalen-brunson-ingressara-no-estudio-inaugural-de-esportes-e-entretenimento-da-variety-em-nova-york\/","title":{"rendered":"Jalen Brunson ingressar\u00e1 no est\u00fadio inaugural de esportes e entretenimento da Variety em Nova York"},"content":{"rendered":"\n<figure><\/figure>\n<\/p>\n<div data-article-body=\"true\" data-body-type=\"bodyblocks\">\n<p class=\"mb-4 text-lg md:leading-8 break-words\">A Variety est\u00e1 trazendo sua aclamada franquia Sports &#038; Entertainment para a cidade de Nova York em seu primeiro est\u00fadio de entrevistas, apresentando conversas com as vozes que moldam o futuro do neg\u00f3cio de esportes e entretenimento em 16 de julho.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">De atletas de elite e propriet\u00e1rios de equipes a profissionais de marketing, executivos de m\u00eddia e l\u00edderes de streaming que redefinem como o conte\u00fado esportivo \u00e9 criado, distribu\u00eddo e consumido, o est\u00fadio reunir\u00e1 as vozes mais influentes da ind\u00fastria em seis conversas que exploram o futuro da narrativa esportiva, do fandom e da cultura.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\"><strong>Mais da variedade<\/strong><\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Depois de um t\u00edtulo hist\u00f3rico do campeonato da NBA em 2026, Jalen Brunson, do New York Knicks, falar\u00e1 com Kristin Lemkau, CEO do JP Morgan Wealth Management, sobre a import\u00e2ncia da educa\u00e7\u00e3o financeira para atletas e o papel de Brunson em inspirar a pr\u00f3xima gera\u00e7\u00e3o como membro do Conselho de Atletas do JPMorganChase.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cO desporto e o entretenimento tornaram-se cada vez mais interligados, influenciando a cultura de forma profunda e duradoura\u201d, disse Dea Lawrence, copresidente e editora da Variety. \u201cEstamos entusiasmados em lan\u00e7ar este novo est\u00fadio de entrevistas em Nova York como um destino privilegiado para conversas esclarecedoras com atletas, criadores, executivos e contadores de hist\u00f3rias que moldam o futuro desta intersec\u00e7\u00e3o din\u00e2mica.\u201d<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">As conversas tamb\u00e9m contar\u00e3o com Jay Williams, personalidade, empres\u00e1rio e investidor da ESPN; Russell Wilson, quarterback campe\u00e3o do Super Bowl, empres\u00e1rio e propriet\u00e1rio de esportes; Jimmie Johnson, sete vezes campe\u00e3o da Nascar Cup e propriet\u00e1rio da equipe Legacy Motor Club; Kristyn Cook, vice-presidente executiva e diretora de ag\u00eancia, marketing e vendas da State Farm; e Carolyn Braff, vice-presidente de esportes e entretenimento da PepsiCo.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Dani Cushion, Diretora de Marketing da Teads, falar\u00e1 sobre as mudan\u00e7as nas formas como os f\u00e3s assistem e interagem com os esportes e as novas oportunidades emergentes para as marcas capturarem a aten\u00e7\u00e3o e gerarem um impacto significativo.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Com o cen\u00e1rio animado e cin\u00e9tico da cidade de Nova York, o est\u00fadio de entrevistas com curadoria da Variety destacar\u00e1 aqueles que est\u00e3o na vanguarda da conversa no mundo convergente dos esportes, entretenimento e streaming.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\"><strong>O melhor da variedade<\/strong><\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Inscreva-se para <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:Variety&apos;s Newsletter;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"https:\/\/cloud.email.variety.com\/signup\/\">Boletim Informativo da Variedade<\/a>. Para as \u00faltimas not\u00edcias, siga-nos no <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:Facebook;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"http:\/\/bit.ly\/31XsHSx\">Facebook<\/a>, <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:Twitter;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"http:\/\/bit.ly\/2TkcoeG\">Twitter<\/a>e <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" data-ylk=\"slk:Instagram;elm:context_link;itc:0;sec:content-canvas;\" data-yga=\"{&quot;yLinkElement&quot;:&quot;link&quot;,&quot;yLinkElementType&quot;:&quot;article_link&quot;}\" href=\"http:\/\/bit.ly\/2TntOHq\">Instagram<\/a>.<\/p>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte www.yahoo.com&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land   \u2019 Source Link <\/em><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>A Variety est\u00e1 trazendo sua aclamada franquia Sports &#038; Entertainment para a cidade de Nova York em seu primeiro est\u00fadio de entrevistas, apresentando conversas com as vozes que moldam o futuro do neg\u00f3cio de esportes e entretenimento em 16 de julho. De atletas de elite e propriet\u00e1rios de equipes a profissionais de marketing, executivos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1827543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827543"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827543\/revisions"}],"predecessor-version":[{"id":1827545,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827543\/revisions\/1827545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827544"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}