{"id":1827606,"date":"2026-07-15T19:06:47","date_gmt":"2026-07-15T19:06:47","guid":{"rendered":"https:\/\/celebrity.land\/pt\/?p=1827606"},"modified":"2026-07-15T19:06:47","modified_gmt":"2026-07-15T19:06:47","slug":"slipknot-recruta-produtor-matt-wallace-para-novas-musicas-temos-tanto-material-provavelmente-pelo-menos-50-arranjos","status":"publish","type":"post","link":"https:\/\/celebrity.land\/pt\/slipknot-recruta-produtor-matt-wallace-para-novas-musicas-temos-tanto-material-provavelmente-pelo-menos-50-arranjos\/","title":{"rendered":"SLIPKNOT recruta produtor MATT WALLACE para novas m\u00fasicas: \u2018Temos tanto material, provavelmente pelo menos 50 arranjos\u2019"},"content":{"rendered":"\n<figure><\/figure>\n<\/p>\n<div>\n<p>Em uma nova entrevista com <b>Ben Giese<\/b>anfitri\u00e3o do <a target=\"_blank\" rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/@ridebynd\">Passeio por Bynd<\/a> podcast, <b>SLIP KNOT<\/b> guitarrista <b>Jim Raiz<\/b> falou sobre o ressurgimento do nu metal, subg\u00eanero do metal que mistura um som pesado com elementos de hip-hop, funk e rock alternativo. Outrora popular no final dos anos 1990 e in\u00edcio dos anos 2000, agora encontrou uma segunda vida entre os jovens ouvintes, gra\u00e7as ao <b>TikTok<\/b> e o renascimento do Y2K. <b>Raiz<\/b> disse (conforme transcrito por <b>BLABBERMOUTH.NET<\/b>): &#8220;Isso acontece, cara. Isso \u00e9 como moda, \u00e9 como filmes. Tudo tem um ciclo. As coisas entram e saem do ciclo&#8230; O que \u00e9 selvagem, porque a nova merda que estamos [<b>SLIPKNOT<\/b>] escrever n\u00e3o soa assim. N\u00e3o estamos divagando ou evoluindo para esse tipo de&#8230; H\u00e1 elementos disso. Quero dizer, n\u00f3s escrevemos como escrevemos, ent\u00e3o sempre teremos um pouco de vibra\u00e7\u00e3o. Mas voc\u00ea n\u00e3o vai ouvir \u2013 por falta de um termo melhor \u2013 um disco de nu metal nosso, se isso faz algum sentido.\u201d<\/p>\n<p><b>Raiz<\/b> continuou: &#8220;N\u00e3o sei se alguma vez fomos nu metal. Acho que surgimos numa \u00e9poca em que o nu metal estava acontecendo, ent\u00e3o foi a\u00ed que ficamos agrupados. Porque quando a New Wave Of American [Heavy] O metal aconteceu, eles nos colocaram nisso, quando eu dava entrevistas de guitarra para revistas. E eu disse, \u2018Espere um minuto. Achei que \u00e9ramos nu metal. Mas agora estamos fazendo entrevistas com <b>CORDEIRO DE DEUS<\/b> e bandas como essa, e eu fico tipo, &#8216;Ok, tanto faz.&#8217;<\/p>\n<p>\u201cPara mim, acho que estamos apenas <b>SLIP KNOT<\/b>\u201d, <b>Jim<\/b> adicionado. \u201cEstamos apenas <b>SLIP KNOT<\/b> m\u00fasica. Eu n\u00e3o acho que haja uma caixa [you can put us in]. Temos tantos elementos. Porque todos na banda v\u00eam de origens musicais diferentes. Tem aquelas bandas que saem e meio que criam suas pr\u00f3prias coisas, onde voc\u00ea pode ouvir, tipo, talvez uma influ\u00eancia aqui e ali. Como quando voc\u00ea ouve <b>U2<\/b>n\u00e3o h\u00e1 realmente nenhuma outra banda que soe como <b>U2<\/b> a menos que eles estejam emulando <b>U2<\/b>in\u00edcio de carreira. Mas eles evolu\u00edram para algo que \u00e9 coisa deles. Isso \u00e9 o que eles fazem. Suponho que voc\u00ea provavelmente poderia colocar <b>MUSA<\/b> nessa categoria, embora eu ou\u00e7a muito <b>RAINHA<\/b> influ\u00eancia em algumas das coisas que [<b>MUSE<\/b>&#8216;s <b>Matt<\/b>] <b>Bellamy<\/b>est\u00e1 fazendo e a maneira como ele escreve e aborda a m\u00fasica. Mas h\u00e1 bandas que n\u00e3o s\u00e3o categoriz\u00e1veis, e eu penso \u2013 n\u00e3o sei se \u00e9 se penso ou espero; N\u00e3o sei qual \u00e9 a palavra certa, espero ou penso, e\/ou ambos &#8211; \u00e9 isso que <b>SLIP KNOT<\/b> \u00e9. At\u00e9 mesmo conversando com o produtor com quem estamos trabalhando &#8211; estamos trabalhando <b>Matt Wallace<\/b> agora para escrever essas coisas &#8211; e h\u00e1 momentos em que apenas sentamos e ouvimos o que acabei de trabalhar e fico tipo, &#8216;Uau, isso \u00e9 incr\u00edvel. Isso n\u00e3o parece nada que eu j\u00e1 tenha ouvido antes, mas h\u00e1 uma familiaridade nisso que parece que tenho ouvido isso durante toda a minha vida. E \u00e9 t\u00e3o org\u00e2nico. \u00c9 s\u00f3 <b>SLIP KNOT<\/b> m\u00fasica.&#8221;<\/p>\n<p>Solicitado a descrever o novo <b>SLIP KNOT<\/b> m\u00fasica em que ele e seus companheiros de banda est\u00e3o trabalhando, <b>Jim<\/b> disse: \u201c\u00c9 <b>SLIP KNOT<\/b>ent\u00e3o teremos um som, mas ao mesmo tempo, tendo [new <b>SLIPKNOT<\/b> drummer] <b>Eloy<\/b> [<b>Casagrande<\/b>]  na banda\u2026 Cara, \u00e9 uma honra poder tocar com aquele cara, e a maneira como estamos abordando isso\u2026 Sim, posso sentar em frente ao meu computador, e posso fazer alguns loops de bateria e come\u00e7ar a escrever riffs e coloc\u00e1-los em camadas, e isso \u00e9 \u00f3timo. E ent\u00e3o eu posso dar para a banda, e <b>Corey<\/b> [<b>Taylor<\/b>, <b>SLIPKNOT<\/b> singer]  posso colocar letras nele e todo esse tipo de coisa. E tem o seu lugar. Mas a maneira como estamos abordando isso, que \u00e9 semelhante \u00e0 forma como foi abordado no in\u00edcio, como uma esp\u00e9cie de vibra\u00e7\u00e3o de banda de garagem. Agora vamos para uma igreja, estamos montando <b>Eloy<\/b>estou montando um equipamento de guitarra e estamos tocando por, tipo, duas horas. E ent\u00e3o, dessas duas horas, voltaremos e, enquanto tocamos, <b>Palha\u00e7o<\/b> [<b>SLIPKNOT<\/b> percussionist <b>Michael Shawn Crahan<\/b>]  estar\u00e1 na sala, com fones de ouvido, e pode come\u00e7ar a tocar conosco, ou pode apenas estar ouvindo o que estamos fazendo. E ele joga o bra\u00e7o para cima ou acerta a luz, e isso \u00e9 uma deixa para o nosso produtor, tipo, &#8216;Isso \u00e9 uma parte.&#8217; Em sua mente, ele est\u00e1 pensando: &#8216;Isso \u00e9 um refr\u00e3o. Isso \u00e9 uma introdu\u00e7\u00e3o. Essa \u00e9 uma linha de verso. Isso \u00e9 uma ponte, qualquer que seja a parte. Mas ent\u00e3o ele olhar\u00e1 para n\u00f3s e dir\u00e1: \u201cFique com isso\u201d. Ou ele dir\u00e1, \u2018Isso foi legal. Ir em frente. V\u00e1 para outro lugar com isso. E ent\u00e3o o que conseguimos fazer foi fazer essas jams e depois fazer uma pausa. <b>Palha\u00e7o<\/b> entrar\u00e1 e eu sentarei com <b>Palha\u00e7o<\/b> e <b>Matt<\/b>nosso produtor, e ele vai come\u00e7ar a fazer os arranjos da m\u00fasica a partir de tudo isso, a partir de improvisos. E \u00e9 t\u00e3o org\u00e2nico e t\u00e3o honesto e t\u00e3o aberto \u00e0 interpreta\u00e7\u00e3o.\u201d<\/p>\n<p><b>Raiz<\/b> continuou: &#8220;Eu n\u00e3o poderia te dizer qual ser\u00e1 a dire\u00e7\u00e3o deste pr\u00f3ximo \u00e1lbum. Eu sei que estou escrevendo alguns dos riffs mais r\u00e1pidos, alguns dos riffs mais mel\u00f3dicos, pesados \u200b\u200be sombrios. Muitos interl\u00fadios realmente bonitos, simplesmente lindos e limpos e coisas assim que est\u00e3o entrando nessas m\u00fasicas. Muito tipo apenas experimental &#8211; eu n\u00e3o quero dizer <b>FLOYD ROSA<\/b>mas talvez em algum lugar naquela casa do leme.\u201d<\/p>\n<p><b>Raiz<\/b> passou a dizer que <b>SLIP KNOT<\/b>A maneira de trabalhar em novas m\u00fasicas agora \u00e9 &#8220;a maneira mais honesta que posso pensar de escrever m\u00fasica&#8230; Quando estou sentado na frente de um computador e estou tentando escrever uma m\u00fasica, \u00e9 artificial. Eu sei que \u00e9 para isso que estou l\u00e1 para fazer. Quando fazemos uma jam, n\u00e3o sabemos o que vai acontecer. Poder\u00edamos come\u00e7ar uma jam que acontece t\u00e3o legal, apenas colocamos uma m\u00fasica de cima a baixo sem sequer pensar sobre isso, porque \u00e0s vezes isso acontece. Poder\u00edamos tocar por duas horas e pode haver duas coisas legais l\u00e1 que poder\u00edamos usar para outra coisa ou qualquer combina\u00e7\u00e3o de todas essas coisas, mas o que ele est\u00e1 fazendo \u00e9 deixar uma banda de nove caras t\u00e3o livres e t\u00e3o abertos que n\u00e3o importa o que seja um riff ou qual seja uma parte&#8230; Se. <b>Mike<\/b> [<b>Thomson<\/b>, <b>SLIPKNOT<\/b> guitarist]  n\u00e3o participou de nenhuma das jams que fizemos, ele pode entrar, pode ouvir um arranjo e pode dizer, tipo, &#8216;Eu sei o que posso fazer com isso, e n\u00e3o vou fazer o que voc\u00ea est\u00e1 fazendo com isso. Vou fazer o que quiser com isso. E eles podem viver juntos. N\u00e3o \u00e9 apenas, tipo, &#8216;N\u00f3s vamos subir, vamos nos encontrar aqui, e vamos tocar em un\u00edssono, e ent\u00e3o vamos para a parte do slam, e ent\u00e3o vai voltar para o verso.&#8217; N\u00e3o \u00e9 nada desse tipo de besteira. \u00c9 literalmente deix\u00e1-lo evoluir de uma forma muito org\u00e2nica e natural, como deveria. E isso \u00e9 dif\u00edcil de fazer quando voc\u00ea n\u00e3o \u00e9 um cantor e compositor. Cantores e compositores podem fazer isso o dia todo, porque tudo o que escrevem sai de si mesmos\u2026\u201d<\/p>\n<p>Elaborando sobre onde <b>SLIP KNOT<\/b> atualmente est\u00e1 em processo de escrita, <b>Jim<\/b> disse: \u201cTemos <i>ent\u00e3o<\/i>, <i>ent\u00e3o<\/i>, <i>ent\u00e3o<\/i>, <i>ent\u00e3o<\/i> muito material &#8211; provavelmente pelo menos 50 arranjos. N\u00e3o estou dizendo que s\u00e3o todas m\u00fasicas completas e que todas precisam de trabalho. Estamos tentando dar um salto, voltar ao <b>&#8216;N\u00e3o somos seu tipo&#8217;<\/b> processo onde come\u00e7ar a trabalhar em algo, lev\u00e1-lo a um n\u00edvel, arquiv\u00e1-lo, trabalhar em outra coisa, voltar a isso, dizer, &#8216;Ok, agora vamos levar isso para outro n\u00edvel&#8217;, e meio que dar aquele salto onde podemos deixar tudo evoluir e, esperan\u00e7osamente, em um ponto chegar onde est\u00e1, tipo, &#8216;N\u00e3o sei se podemos deixar isso evoluir.&#8217; Mais ou menos como fazer um filme. Muitos diretores dizem que n\u00e3o terminam de fazer um filme; eles simplesmente abandonam o projeto.\u201d<\/p>\n<p>H\u00e1 mais de dois anos, <b>SLIP KNOT<\/b> revelou que uma nova m\u00fasica <b>\u201cMuito tempo que voc\u00ea morra\u201d<\/b> foi gravado durante algumas das primeiras sess\u00f5es com <b>Casagrande<\/b>.<\/p>\n<p><b>SLIP KNOT<\/b>\u00faltimo \u00e1lbum de <b>\u201cO fim, at\u00e9 agora\u201d<\/b>chegou em agosto de 2022. Marcou o \u00faltimo LP completo da banda antes da sa\u00edda dos dois tecladistas <b>Craig Jones<\/b>que deixou o grupo em junho de 2023, e baterista <b>Jay Weinberg<\/b>que foi substitu\u00eddo por <b>Casagrande<\/b>.<\/p>\n<p>No outono passado, <b>SLIP KNOT<\/b> vendeu seu cat\u00e1logo de m\u00fasicas para <b>Parceiros de capital HarbourView<\/b>. O acordo inclu\u00eda os direitos de <b>SLIP KNOT<\/b>direitos autorais de masters de publica\u00e7\u00e3o e grava\u00e7\u00e3o. Segundo informa\u00e7\u00f5es, cobria o cat\u00e1logo de arquivo da banda, mas n\u00e3o se estendia a lan\u00e7amentos futuros.<\/p>\n<p>Desde o lan\u00e7amento de seu \u00e1lbum de estreia em 1999 <b>SLIP KNOT<\/b> capturou um <b>Pr\u00eamio Grammy<\/b> ao lado de 11 indica\u00e7\u00f5es, obteve uma s\u00e9rie de certifica\u00e7\u00f5es de \u00e1lbuns de platina e ouro em todo o mundo e registrou bilh\u00f5es de streams globais e visualiza\u00e7\u00f5es de v\u00eddeos at\u00e9 o momento. <b>Pedra rolando<\/b> citou o \u00e1lbum seminal de 2001, que vendeu platina <b>\u201cIowa\u201d<\/b> entre os \u201c100 melhores \u00e1lbuns de metal de todos os tempos\u201d, enquanto <b>A campainha<\/b> atestou: \u201cEles s\u00e3o a banda pesada mais importante de sua \u00e9poca\u201d.<\/p>\n<p><b>\u201cO fim, at\u00e9 agora\u201d<\/b>alcan\u00e7ou o primeiro lugar na parada de vendas de \u00e1lbuns mais vendidos da Billboard e o segundo lugar na Billboard 200, marcando seu sexto \u00e1lbum no Top 10 da Billboard 200. Um novo \u00e1lbum de <b>SLIP KNOT<\/b> \u00e9 um evento global e <b>\u201cO fim, at\u00e9 agora\u201d<\/b> continuou a ascens\u00e3o da banda nas paradas globais, com estreias em primeiro lugar no Reino Unido, Austr\u00e1lia, Alemanha, Su\u00ed\u00e7a e M\u00e9xico, bem como estreias no Top 3 no Canad\u00e1, Nova Zel\u00e2ndia, Finl\u00e2ndia, Su\u00e9cia, Jap\u00e3o e B\u00e9lgica. <b>SLIP KNOT<\/b>\u00e1lbum anterior de 2019 <b>\u201cN\u00e3o somos seu tipo\u201d<\/b>marcado <b>SLIP KNOT<\/b>O terceiro n\u00famero 1 consecutivo na Billboard 200, junto com a estreia em primeiro lugar nas paradas oficiais de \u00e1lbuns de doze pa\u00edses ao redor do mundo, incluindo Reino Unido, Austr\u00e1lia, Canad\u00e1 e M\u00e9xico, com estreias no Top 5 em mais doze pa\u00edses. incluindo Alemanha, Fran\u00e7a e Su\u00e9cia.<\/p>\n<p>Cr\u00e9dito da foto: <b>Jonathan Weiner<\/b><\/p>\n<div class=\"jeg_video_container jeg_video_content\"><\/div>\n<\/div>\n<p><em>  &#8216;O artigo anterior pode incluir informa\u00e7\u00f5es divulgadas por terceiros&#8217; <\/em><\/p>\n<p><em>  &#8216;Alguns detalhes deste artigo foram extra\u00eddos da seguinte fonte blabbermouth.net&#8217; <\/em><\/p>\n<p><em> \u2018 O artigo anterior foi obtido e traduzido do site internacional da celebrity.land   \u2019 Source Link <\/em><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Em uma nova entrevista com Ben Gieseanfitri\u00e3o do Passeio por Bynd podcast, SLIP KNOT guitarrista Jim Raiz falou sobre o ressurgimento do nu metal, subg\u00eanero do metal que mistura um som pesado com elementos de hip-hop, funk e rock alternativo. Outrora popular no final dos anos 1990 e in\u00edcio dos anos 2000, agora encontrou uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1827607,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1827606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica"],"_links":{"self":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/comments?post=1827606"}],"version-history":[{"count":1,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827606\/revisions"}],"predecessor-version":[{"id":1827608,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/posts\/1827606\/revisions\/1827608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media\/1827607"}],"wp:attachment":[{"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/media?parent=1827606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/categories?post=1827606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/celebrity.land\/pt\/wp-json\/wp\/v2\/tags?post=1827606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}